{"id":9751,"date":"2015-11-23T00:00:00","date_gmt":"2015-11-23T00:00:00","guid":{"rendered":"https:\/\/mwc-cmm.org\/the-gift-of-conversations-at-assembly-pa-2015-4\/"},"modified":"2024-12-10T17:13:48","modified_gmt":"2024-12-10T17:13:48","slug":"the-gift-of-conversations-at-assembly-pa-2015-4","status":"publish","type":"post","link":"https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/","title":{"rendered":"Le don des conversations au Rassemblement PA 2015"},"content":{"rendered":"<p><strong>Cercles d\u2019amiti\u00e9 et activit\u00e9s<\/strong><\/p>\n<p>Il y a eu tellement de belles choses \u00e0 la Conf\u00e9rence Mennonite Mondiale [Rassemblement PA 2015]. C\u2019\u00e9tait la premi\u00e8re fois que j\u2019y allais et j\u2019ai vraiment aim\u00e9 les cultes d\u2019adoration, en particulier leur diversit\u00e9 (je n\u2019avais aucune id\u00e9e de ce qu\u2019avait l\u2019air un culte japonais!). Mais peut-\u00eatre la raison la plus importante pour laquelle je voulais aller \u00e0 PA 2015 \u00e9tait de rencontrer et d\u2019\u00e9changer avec des mennonites de partout dans le monde. Les cercles d\u2019amiti\u00e9 et les activit\u00e9s ont \u00e9t\u00e9 les deux meilleurs endroits pour avoir des conversations.<\/p>\n<p>Chaque jour, apr\u00e8s le culte d\u2019ouverture, nous \u00e9tions invit\u00e9s \u00e0 nous joindre \u00e0 un cercle d\u2019amiti\u00e9. Au d\u00e9but, la conversation n\u2019\u00e9tait pas ais\u00e9e car nous apprenions \u00e0 nous conna\u00eetre les uns les autres. On nous a donn\u00e9 des questions \u00e0 discuter, cela a aid\u00e9. \u00ca la fin de la semaine, les questions nous ont incit\u00e9s \u00e0 r\u00e9fl\u00e9chir sur un sujet controvers\u00e9. Apr\u00e8s les cultes extraordinaires de la semaine, j\u2019\u00e9tais curieux de voir comment notre cercle (quatre Canadiens et un Philippin) allait  traiter le sujet. J\u2019ai \u00e9t\u00e9 d\u00e9\u00e7u. On pouvait presque voir les barri\u00e8res relationnelles, qui avaient pourtant \u00e9t\u00e9 si soigneusement abolies, le groupe a fait un pas en arri\u00e8re se fractionnant lui-m\u00eame dans divers camps th\u00e9ologiques.<\/p>\n<p>Il \u00e9tait clair que ce probl\u00e8me th\u00e9ologique n\u2019allait pas se r\u00e9soudre en 30 minutes, mais cela n\u2019a pas emp\u00each\u00e9 des personnes de faire valoir leur verset biblique et leur th\u00e9ologie de choix dont tous les participants avaient \u00e9videmment d\u00e9j\u00e0 entendu parler. Ce qui aurait pu \u00eatre l\u2019occasion de r\u00e9affirmer nos points communs et notre volont\u00e9 de rester en communion tout en conservant nos convictions particuli\u00e8res s\u2019est plut\u00f4t r\u00e9duit en bouillie \u00ab j\u2019accepte le d\u00e9saccord \u00bb.<\/p>\n<p>Cependant, les cercles d\u2019amiti\u00e9 n\u2019ont \u00e9t\u00e9 qu\u2019un moment dans la journ\u00e9e. Au premier jour complet du rassemblement, j\u2019ai particip\u00e9 \u00e0 une randonn\u00e9e dans une portion du sentier des Appalaches. La plupart d\u2019entre nous ne nous connaissions pas; nous \u00e9tions tellement concentr\u00e9s sur la marche que c\u2019est seulement \u00e0 la moiti\u00e9 de la randonn\u00e9e que je me suis aper\u00e7u que personne ne parlait r\u00e9ellement. Durant une pause, j\u2019ai finalement engag\u00e9 une conversation avec une femme du Royaume-Uni qui travaille avec le R\u00e9seau Anabaptiste. C\u2019\u00e9tait formidable de parler avec elle d\u2019autant plus que j\u2019avais lu <em>The Naked Anabaptist<\/em> (<em>Radicalement chr\u00e9tien<\/em>) il y a quelques ann\u00e9es. Nous avons parl\u00e9 de plusieurs choses, notamment des fa\u00e7ons diff\u00e9rentes que nos pays se souviennent des v\u00e9t\u00e9rans et des diverses r\u00e9ponses que les \u00e9glises de paix ont apport\u00e9es.  <\/p>\n<p>Sur le chemin du retour, j\u2019ai eu une conversation avec un \u00e9tudiant d\u2019un S\u00e9minaire aux \u00c9tats-Unis. Comme moi, il s\u2019est converti tardivement \u00e0 la tradition anabaptiste; nous avons parl\u00e9 de nos exp\u00e9riences. Il venait d\u2019un arri\u00e8re-plan pentec\u00f4tiste et manquait parfois l\u2019accent mis sur le Saint-Esprit. Bien que je ne provienne pas d\u2019un milieu pentec\u00f4tiste, je comprenais ce sentiment. Il m\u2019a aussi recommand\u00e9 la lecture d\u2019un auteur que je lirai. Ce fut deux moments \u00e9difiants de conversation et de solidarit\u00e9 sur la montagne.<\/p>\n<p>Dans mon cercle d\u2019amiti\u00e9 et pendant les activit\u00e9s, j\u2019ai exp\u00e9riment\u00e9 deux types de conversation : guid\u00e9e et naturelle. Les deux sont pertinentes, mais les conversations engag\u00e9es pendant que nous faisons des choses ensemble naturellement (dans le bus de retour \u00e0 l\u2019h\u00f4tel, autour de la table \u00e0 manger ou sur la montagne) ont \u00e9t\u00e9 celles o\u00f9 des relations et une compr\u00e9hension mutuelle se sont b\u00e2ties. Pour moi, c\u2019est tout l\u2019int\u00e9r\u00eat d\u2019aller \u00e0 la Conf\u00e9rence Mennonite Mondiale [Rassemblement].<\/p>\n<p>Cette r\u00e9flexion fait partie du num\u00e9ro de septembre 2015 de <em>Lendrum Grace Notes<\/em>, \u00ab Mennonites: A Global Family \u00bb. Cliquez <a href=\"\/sites\/default\/files\/website_files\/2015-09_grace_notes_for_web.pdf\">ici<\/a> pour voir tout le magazine en anglais.<\/p>\n<p>*Joignez-vous \u00e0 la famille anabaptiste mondiale, le Dimanche de la Fraternit\u00e9 Mondiale en janvier 2016, pour c\u00e9l\u00e9brer le th\u00e8me de PA 2015 <em>En marche avec Dieu<\/em>. Cliquez <a href=\"https:\/\/www.mwc-cmm.org\/article\/dimanche-fraternite-mondiale?language=fr\">ici<\/a> pour l\u2019acc\u00e8s \u00e0 des ressources pour votre \u00e9glise. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>NULL<\/p>\n","protected":false},"author":1,"featured_media":87282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[1553,1893],"network":[],"eventcategory":[1494],"class_list":["post-9751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-assemblee-2","tag-pa2015","eventcategory-assembly-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le don des conversations au Rassemblement PA 2015 - Mennonite World Conference<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le don des conversations au Rassemblement PA 2015 - Mennonite World Conference\" \/>\n<meta property=\"og:description\" content=\"NULL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Mennonite World Conference\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MennoniteWorldConference\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-23T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-10T17:13:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/lendrum_testimony-20150722_heike-martin_0343.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mennworldcon\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/fr\\\/stories\\\/the-gift-of-conversations-at-assembly-pa-2015-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/fr\\\/stories\\\/the-gift-of-conversations-at-assembly-pa-2015-4\\\/\"},\"author\":{\"name\":\"mennworldcon\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/person\\\/11f6ae0d7d1868ba20a1cc27f067c836\"},\"headline\":\"Le don des conversations au Rassemblement PA 2015\",\"datePublished\":\"2015-11-23T00:00:00+00:00\",\"dateModified\":\"2024-12-10T17:13:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/fr\\\/stories\\\/the-gift-of-conversations-at-assembly-pa-2015-4\\\/\"},\"wordCount\":729,\"publisher\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/fr\\\/stories\\\/the-gift-of-conversations-at-assembly-pa-2015-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/lendrum_testimony-20150722_heike-martin_0343.jpg\",\"keywords\":[\"Assembl\u00e9e\",\"PA2015\"],\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/fr\\\/stories\\\/the-gift-of-conversations-at-assembly-pa-2015-4\\\/\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/fr\\\/stories\\\/the-gift-of-conversations-at-assembly-pa-2015-4\\\/\",\"name\":\"Le don des conversations au Rassemblement PA 2015 - Mennonite World Conference\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/fr\\\/stories\\\/the-gift-of-conversations-at-assembly-pa-2015-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/fr\\\/stories\\\/the-gift-of-conversations-at-assembly-pa-2015-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/lendrum_testimony-20150722_heike-martin_0343.jpg\",\"datePublished\":\"2015-11-23T00:00:00+00:00\",\"dateModified\":\"2024-12-10T17:13:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/fr\\\/stories\\\/the-gift-of-conversations-at-assembly-pa-2015-4\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mwc-cmm.org\\\/fr\\\/stories\\\/the-gift-of-conversations-at-assembly-pa-2015-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/fr\\\/stories\\\/the-gift-of-conversations-at-assembly-pa-2015-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/lendrum_testimony-20150722_heike-martin_0343.jpg\",\"contentUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/lendrum_testimony-20150722_heike-martin_0343.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/fr\\\/stories\\\/the-gift-of-conversations-at-assembly-pa-2015-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mwc-cmm.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le don des conversations au Rassemblement PA 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/\",\"name\":\"Mennonite World Conference\",\"description\":\"A communion of Anabaptist-related churches\",\"publisher\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\"},\"alternateName\":\"MWC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\",\"name\":\"Mennonite World Conference\",\"alternateName\":\"MWC\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/MWC_Sig_Blue_Horiz_webheader1-logo.svg\",\"contentUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/MWC_Sig_Blue_Horiz_webheader1-logo.svg\",\"width\":786,\"height\":82,\"caption\":\"Mennonite World Conference\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MennoniteWorldConference\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mennonite-world-conference-mwc\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mwcmm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/mwccmm\",\"https:\\\/\\\/bsky.app\\\/profile\\\/mwcmm.bsky.social\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/person\\\/11f6ae0d7d1868ba20a1cc27f067c836\",\"name\":\"mennworldcon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g\",\"caption\":\"mennworldcon\"},\"sameAs\":[\"https:\\\/\\\/mwc-cmm.org\"],\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/fr\\\/stories\\\/author\\\/mennworldcon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le don des conversations au Rassemblement PA 2015 - Mennonite World Conference","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/","og_locale":"fr_FR","og_type":"article","og_title":"Le don des conversations au Rassemblement PA 2015 - Mennonite World Conference","og_description":"NULL","og_url":"https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/","og_site_name":"Mennonite World Conference","article_publisher":"https:\/\/www.facebook.com\/MennoniteWorldConference","article_published_time":"2015-11-23T00:00:00+00:00","article_modified_time":"2024-12-10T17:13:48+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/lendrum_testimony-20150722_heike-martin_0343.jpg","type":"image\/jpeg"}],"author":"mennworldcon","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/#article","isPartOf":{"@id":"https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/"},"author":{"name":"mennworldcon","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/person\/11f6ae0d7d1868ba20a1cc27f067c836"},"headline":"Le don des conversations au Rassemblement PA 2015","datePublished":"2015-11-23T00:00:00+00:00","dateModified":"2024-12-10T17:13:48+00:00","mainEntityOfPage":{"@id":"https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/"},"wordCount":729,"publisher":{"@id":"https:\/\/mwc-cmm.org\/en\/#organization"},"image":{"@id":"https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/#primaryimage"},"thumbnailUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/lendrum_testimony-20150722_heike-martin_0343.jpg","keywords":["Assembl\u00e9e","PA2015"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/","url":"https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/","name":"Le don des conversations au Rassemblement PA 2015 - Mennonite World Conference","isPartOf":{"@id":"https:\/\/mwc-cmm.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/#primaryimage"},"image":{"@id":"https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/#primaryimage"},"thumbnailUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/lendrum_testimony-20150722_heike-martin_0343.jpg","datePublished":"2015-11-23T00:00:00+00:00","dateModified":"2024-12-10T17:13:48+00:00","breadcrumb":{"@id":"https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/#primaryimage","url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/lendrum_testimony-20150722_heike-martin_0343.jpg","contentUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/lendrum_testimony-20150722_heike-martin_0343.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/mwc-cmm.org\/fr\/stories\/the-gift-of-conversations-at-assembly-pa-2015-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mwc-cmm.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Le don des conversations au Rassemblement PA 2015"}]},{"@type":"WebSite","@id":"https:\/\/mwc-cmm.org\/en\/#website","url":"https:\/\/mwc-cmm.org\/en\/","name":"Mennonite World Conference","description":"A communion of Anabaptist-related churches","publisher":{"@id":"https:\/\/mwc-cmm.org\/en\/#organization"},"alternateName":"MWC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mwc-cmm.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mwc-cmm.org\/en\/#organization","name":"Mennonite World Conference","alternateName":"MWC","url":"https:\/\/mwc-cmm.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2026\/01\/MWC_Sig_Blue_Horiz_webheader1-logo.svg","contentUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2026\/01\/MWC_Sig_Blue_Horiz_webheader1-logo.svg","width":786,"height":82,"caption":"Mennonite World Conference"},"image":{"@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MennoniteWorldConference","https:\/\/www.linkedin.com\/company\/mennonite-world-conference-mwc\/","https:\/\/www.instagram.com\/mwcmm\/","https:\/\/www.youtube.com\/user\/mwccmm","https:\/\/bsky.app\/profile\/mwcmm.bsky.social"]},{"@type":"Person","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/person\/11f6ae0d7d1868ba20a1cc27f067c836","name":"mennworldcon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g","caption":"mennworldcon"},"sameAs":["https:\/\/mwc-cmm.org"],"url":"https:\/\/mwc-cmm.org\/fr\/stories\/author\/mennworldcon\/"}]}},"_links":{"self":[{"href":"https:\/\/mwc-cmm.org\/fr\/wp-json\/wp\/v2\/posts\/9751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mwc-cmm.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mwc-cmm.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/fr\/wp-json\/wp\/v2\/comments?post=9751"}],"version-history":[{"count":0,"href":"https:\/\/mwc-cmm.org\/fr\/wp-json\/wp\/v2\/posts\/9751\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/fr\/wp-json\/wp\/v2\/media\/87282"}],"wp:attachment":[{"href":"https:\/\/mwc-cmm.org\/fr\/wp-json\/wp\/v2\/media?parent=9751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mwc-cmm.org\/fr\/wp-json\/wp\/v2\/categories?post=9751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mwc-cmm.org\/fr\/wp-json\/wp\/v2\/tags?post=9751"},{"taxonomy":"network","embeddable":true,"href":"https:\/\/mwc-cmm.org\/fr\/wp-json\/wp\/v2\/network?post=9751"},{"taxonomy":"eventcategory","embeddable":true,"href":"https:\/\/mwc-cmm.org\/fr\/wp-json\/wp\/v2\/eventcategory?post=9751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}