{"id":9497,"date":"2024-08-28T00:00:00","date_gmt":"2024-08-28T00:00:00","guid":{"rendered":"https:\/\/mwc-cmm.org\/continuous-movement-and-a-contrite-heart-2\/"},"modified":"2024-12-10T18:06:45","modified_gmt":"2024-12-10T18:06:45","slug":"movimiento-continuo-y-corazon-contrito","status":"publish","type":"post","link":"https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/","title":{"rendered":"Movimiento continuo y coraz\u00f3n contrito"},"content":{"rendered":"<p>\u201cNo vivan ya seg\u00fan los criterios del tiempo presente; al contrario, cambien su manera de pensar para que as\u00ed cambie su manera de vivir y lleguen a conocer la voluntad de Dios, es decir, lo que es bueno, lo que le es grato, lo que es perfecto.\u201d Romanos 12:2 (DHH)<\/p>\n<p>Renovaci\u00f3n es el nombre que el Congreso Mundial Menonita le ha dado a una d\u00e9cada de eventos regionales en torno a la memoria de los cinco siglos de nuestra existencia como comunidad de fe.<\/p>\n<p>Nos aproximamos a estos diez a\u00f1os de conmemoraciones centr\u00e1ndonos en nuestra historia desde una perspectiva mundial, ecum\u00e9nica y transcultural.<\/p>\n<p>Estas palabras del ap\u00f3stol Pablo nos ayudan a recordar el pasado y mirar hacia el futuro.<\/p>\n<p>Expresamos gratitud a Dios por la herencia de fe que hemos recibido.<\/p>\n<p>Pero tambi\u00e9n venimos ante el Se\u00f1or con un esp\u00edritu de arrepentimiento y renovaci\u00f3n, comprometidos a aprender del pasado y llegar a conocer m\u00e1s a Dios tanto aqu\u00ed y ahora como en los a\u00f1os venideros.<\/p>\n<h4>Transformaci\u00f3n<\/h4>\n<p>Consideramos c\u00f3mo nuestra tradici\u00f3n anabautista ha entendido el discipulado como un proceso continuo de transformaci\u00f3n.<\/p>\n<p>En primer lugar: la transformaci\u00f3n es un camino en el que renunciamos a ciertas cosas y asumimos cosas nuevas.<\/p>\n<p>Implica movimiento continuo. Abandonamos lugares constantemente y avanzamos. Actuamos en contra del esp\u00edritu religioso que sostiene la certeza absoluta de las doctrinas, los dogmas y la \u00e9tica; afirmamos la necesidad de renovar nuestra mente, y por lo tanto, estamos dispuestos a desafiar las creencias y la \u00e9tica como lo hicieron nuestros antepasados espirituales en el siglo XVI.<\/p>\n<p>En segundo lugar: la transformaci\u00f3n en la Biblia nunca es una experiencia individualista.<\/p>\n<p>Siempre es comunitaria. La hacemos juntos porque requiere di\u00e1logo e interdependencia.<\/p>\n<p>La diversidad de posturas de nuestra comunidad nos permite corregir el rumbo en el proceso de transformaci\u00f3n.<\/p>\n<h4>Centrados en Jes\u00fas<\/h4>\n<p>Nuestros hermanos y hermanas nos ayudan a descubrir aquellas cosas que necesitamos cambiar, renunciar o incorporar para llegar a ser como Jes\u00fas.<\/p>\n<p>Y ello nos lleva al tercer comentario b\u00edblico o componente de transformaci\u00f3n: la persona de Jes\u00fas.<\/p>\n<p>No cualquier cambio es v\u00e1lido. Como seguidores de Jes\u00fas, no podemos apoyar la transformaci\u00f3n en cualquier direcci\u00f3n.<\/p>\n<p>Para ser disc\u00edpulos fieles, los cambios en nuestras creencias y \u00e9tica deben hacerse para que lleguemos a ser semejantes al car\u00e1cter y a la persona de Jes\u00fas.<\/p>\n<p>Como se\u00f1ala Pablo, \u201chasta que todos lleguemos a estar unidos por la fe y el conocimiento del Hijo de Dios, y alcancemos la edad adulta, que corresponde a la plena madurez de Cristo\u201d. (Efesios 4:13)<\/p>\n<p>La transformaci\u00f3n en unidad es un desaf\u00edo que enfrentamos hist\u00f3ricamente en el mundo anabautista.<\/p>\n<p>Muy a menudo los movimientos de renovaci\u00f3n han enfrentado el rechazo que producen las divisiones.<\/p>\n<p>La transformaci\u00f3n no siempre se ha dado en torno al car\u00e1cter de Jes\u00fas.<\/p>\n<p>Por eso hoy necesitamos recuperar la visi\u00f3n del Congreso Mundial Menonita: Quisi\u00e9ramos ser una iglesia mundial en la que seguimos a Jes\u00fas, vivimos la unidad y construimos la paz.<\/p>\n<p>Somos un cuerpo de m\u00e1s de diez mil congregaciones locales distribuidas en *110 iglesias nacionales que se encuentran repartidas por todo el mundo, con m\u00e1s de 1,5 millones de creyentes bautizados.<\/p>\n<p>Nos necesitamos mutuamente para ser transformados a la imagen de Jes\u00fas.<\/p>\n<p>Mientras damos gracias a Dios por las oportunidades de ser transformados, mantengamos tambi\u00e9n una actitud de arrepentimiento por nuestras divisiones.<\/p>\n<p>Pidamos perd\u00f3n por nuestra renuencia a cambiar.<\/p>\n<p>Arrepint\u00e1monos de nuestro orgullo y de la actitud de juzgar el proceso de transformaci\u00f3n de los dem\u00e1s, en lugar de participar en \u00e9l con amor y paciencia.<\/p>\n<p>Procuremos la renovaci\u00f3n desde un coraz\u00f3n contrito que reconoce la necesidad de transformaci\u00f3n continua.<\/p>\n<p>Que juntos podamos ser transformados a la imagen de Jes\u00fas.<\/p>\n<p><em>\u2014C\u00e9sar Garc\u00eda<\/em>, <em>secretario general del Congreso Mundial Menonita, es oriundo de Colombia y reside en Kitchener, Ontario, Canad\u00e1.<\/em><\/p>\n<p><em><span style=\"font-size:12px\">*<\/span>N\u00famero de iglesias miembros del CMM tras las reuniones del Comit\u00e9 Ejecutivo en Brasil, abril de 2024.<\/em><\/p>\n<hr>\n<p><a href=\"https:\/\/mwc-cmm.org\/es\/resources\/correo-2024-392-3\"><img decoding=\"async\" alt=\"Correo 39.2&amp;3\" height=\"75\" data-src=\"\/sites\/default\/files\/website_files_2020\/sp_1.jpg\" style=\"--smush-placeholder-width: 825px; --smush-placeholder-aspect-ratio: 825\/75;float:left\" width=\"825\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cNo vivan ya seg\u00fan los criterios del tiempo presente; al contrario, cambien su manera de pensar para que as\u00ed cambie su manera de vivir y lleguen a conocer la voluntad de Dios, es decir, lo que es bueno, lo que le es grato, lo que es perfecto.\u201d Romanos 12:2 (DHH) Renovaci\u00f3n es el nombre que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":98450,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"network":[1306],"eventcategory":[],"class_list":["post-9497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","network-courier-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Movimiento continuo y coraz\u00f3n contrito - Mennonite World Conference<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Movimiento continuo y coraz\u00f3n contrito - Mennonite World Conference\" \/>\n<meta property=\"og:description\" content=\"\u201cNo vivan ya seg\u00fan los criterios del tiempo presente; al contrario, cambien su manera de pensar para que as\u00ed cambie su manera de vivir y lleguen a conocer la voluntad de Dios, es decir, lo que es bueno, lo que le es grato, lo que es perfecto.\u201d Romanos 12:2 (DHH) Renovaci\u00f3n es el nombre que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/\" \/>\n<meta property=\"og:site_name\" content=\"Mennonite World Conference\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MennoniteWorldConference\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-28T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-10T18:06:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/202404irmasulistyorinip1090551-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mennworldcon\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/movimiento-continuo-y-corazon-contrito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/movimiento-continuo-y-corazon-contrito\\\/\"},\"author\":{\"name\":\"mennworldcon\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/person\\\/11f6ae0d7d1868ba20a1cc27f067c836\"},\"headline\":\"Movimiento continuo y coraz\u00f3n contrito\",\"datePublished\":\"2024-08-28T00:00:00+00:00\",\"dateModified\":\"2024-12-10T18:06:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/movimiento-continuo-y-corazon-contrito\\\/\"},\"wordCount\":705,\"publisher\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/movimiento-continuo-y-corazon-contrito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/202404irmasulistyorinip1090551-scaled.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/movimiento-continuo-y-corazon-contrito\\\/\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/movimiento-continuo-y-corazon-contrito\\\/\",\"name\":\"Movimiento continuo y coraz\u00f3n contrito - Mennonite World Conference\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/movimiento-continuo-y-corazon-contrito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/movimiento-continuo-y-corazon-contrito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/202404irmasulistyorinip1090551-scaled.jpg\",\"datePublished\":\"2024-08-28T00:00:00+00:00\",\"dateModified\":\"2024-12-10T18:06:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/movimiento-continuo-y-corazon-contrito\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/movimiento-continuo-y-corazon-contrito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/movimiento-continuo-y-corazon-contrito\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/202404irmasulistyorinip1090551-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/202404irmasulistyorinip1090551-scaled.jpg\",\"width\":2560,\"height\":1708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/movimiento-continuo-y-corazon-contrito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Movimiento continuo y coraz\u00f3n contrito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/\",\"name\":\"Mennonite World Conference\",\"description\":\"A communion of Anabaptist-related churches\",\"publisher\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\"},\"alternateName\":\"MWC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\",\"name\":\"Mennonite World Conference\",\"alternateName\":\"MWC\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/MWC_Sig_Blue_Horiz_webheader1-logo.svg\",\"contentUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/MWC_Sig_Blue_Horiz_webheader1-logo.svg\",\"width\":786,\"height\":82,\"caption\":\"Mennonite World Conference\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MennoniteWorldConference\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mennonite-world-conference-mwc\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mwcmm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/mwccmm\",\"https:\\\/\\\/bsky.app\\\/profile\\\/mwcmm.bsky.social\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/person\\\/11f6ae0d7d1868ba20a1cc27f067c836\",\"name\":\"mennworldcon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g\",\"caption\":\"mennworldcon\"},\"sameAs\":[\"https:\\\/\\\/mwc-cmm.org\"],\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/author\\\/mennworldcon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Movimiento continuo y coraz\u00f3n contrito - Mennonite World Conference","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/","og_locale":"es_ES","og_type":"article","og_title":"Movimiento continuo y coraz\u00f3n contrito - Mennonite World Conference","og_description":"\u201cNo vivan ya seg\u00fan los criterios del tiempo presente; al contrario, cambien su manera de pensar para que as\u00ed cambie su manera de vivir y lleguen a conocer la voluntad de Dios, es decir, lo que es bueno, lo que le es grato, lo que es perfecto.\u201d Romanos 12:2 (DHH) Renovaci\u00f3n es el nombre que [&hellip;]","og_url":"https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/","og_site_name":"Mennonite World Conference","article_publisher":"https:\/\/www.facebook.com\/MennoniteWorldConference","article_published_time":"2024-08-28T00:00:00+00:00","article_modified_time":"2024-12-10T18:06:45+00:00","og_image":[{"width":2560,"height":1708,"url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/202404irmasulistyorinip1090551-scaled.jpg","type":"image\/jpeg"}],"author":"mennworldcon","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/#article","isPartOf":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/"},"author":{"name":"mennworldcon","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/person\/11f6ae0d7d1868ba20a1cc27f067c836"},"headline":"Movimiento continuo y coraz\u00f3n contrito","datePublished":"2024-08-28T00:00:00+00:00","dateModified":"2024-12-10T18:06:45+00:00","mainEntityOfPage":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/"},"wordCount":705,"publisher":{"@id":"https:\/\/mwc-cmm.org\/en\/#organization"},"image":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/#primaryimage"},"thumbnailUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/202404irmasulistyorinip1090551-scaled.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/","url":"https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/","name":"Movimiento continuo y coraz\u00f3n contrito - Mennonite World Conference","isPartOf":{"@id":"https:\/\/mwc-cmm.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/#primaryimage"},"image":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/#primaryimage"},"thumbnailUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/202404irmasulistyorinip1090551-scaled.jpg","datePublished":"2024-08-28T00:00:00+00:00","dateModified":"2024-12-10T18:06:45+00:00","breadcrumb":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/#primaryimage","url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/202404irmasulistyorinip1090551-scaled.jpg","contentUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/202404irmasulistyorinip1090551-scaled.jpg","width":2560,"height":1708},{"@type":"BreadcrumbList","@id":"https:\/\/mwc-cmm.org\/es\/stories\/movimiento-continuo-y-corazon-contrito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mwc-cmm.org\/es\/"},{"@type":"ListItem","position":2,"name":"Movimiento continuo y coraz\u00f3n contrito"}]},{"@type":"WebSite","@id":"https:\/\/mwc-cmm.org\/en\/#website","url":"https:\/\/mwc-cmm.org\/en\/","name":"Mennonite World Conference","description":"A communion of Anabaptist-related churches","publisher":{"@id":"https:\/\/mwc-cmm.org\/en\/#organization"},"alternateName":"MWC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mwc-cmm.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mwc-cmm.org\/en\/#organization","name":"Mennonite World Conference","alternateName":"MWC","url":"https:\/\/mwc-cmm.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2026\/01\/MWC_Sig_Blue_Horiz_webheader1-logo.svg","contentUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2026\/01\/MWC_Sig_Blue_Horiz_webheader1-logo.svg","width":786,"height":82,"caption":"Mennonite World Conference"},"image":{"@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MennoniteWorldConference","https:\/\/www.linkedin.com\/company\/mennonite-world-conference-mwc\/","https:\/\/www.instagram.com\/mwcmm\/","https:\/\/www.youtube.com\/user\/mwccmm","https:\/\/bsky.app\/profile\/mwcmm.bsky.social"]},{"@type":"Person","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/person\/11f6ae0d7d1868ba20a1cc27f067c836","name":"mennworldcon","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g","caption":"mennworldcon"},"sameAs":["https:\/\/mwc-cmm.org"],"url":"https:\/\/mwc-cmm.org\/es\/stories\/author\/mennworldcon\/"}]}},"_links":{"self":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/posts\/9497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/comments?post=9497"}],"version-history":[{"count":0,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/posts\/9497\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/media\/98450"}],"wp:attachment":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/media?parent=9497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/categories?post=9497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/tags?post=9497"},{"taxonomy":"network","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/network?post=9497"},{"taxonomy":"eventcategory","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/eventcategory?post=9497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}