{"id":9151,"date":"2021-11-22T00:00:00","date_gmt":"2021-11-22T00:00:00","guid":{"rendered":"https:\/\/mwc-cmm.org\/believe-and-be-baptized-a-global-conversation-on-baptism-2\/"},"modified":"2024-12-10T18:03:59","modified_gmt":"2024-12-10T18:03:59","slug":"crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo","status":"publish","type":"post","link":"https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/","title":{"rendered":"\u201cCrean y sean bautizados: Un di\u00e1logo mundial sobre el bautismo\u201d"},"content":{"rendered":"<p><em>Tras un di\u00e1logo de cinco a\u00f1os con te\u00f3logos de las tradiciones cat\u00f3lica romana y luterana, el Comit\u00e9 de Fe y Vida invit\u00f3 a los miembros del Congreso Mundial Menonita a considerar juntos nuestras pr\u00e1cticas anabautistas en Renovaci\u00f3n 2027, en dos seminarios web titulados, \u201cCrean y sean bautizados: Un di\u00e1logo mundial sobre el bautismo\u201d.<\/em><\/p>\n<hr \/>\n<h2>Contexto b\u00edblico, teol\u00f3gico e hist\u00f3rico del bautismo de creyentes<\/h2>\n<p>El 21 de enero de 1525, un peque\u00f1o grupo de j\u00f3venes se reuni\u00f3 en secreto en la ciudad suiza de Z\u00farich para un culto inusual. Hab\u00edan sido criados en la tradici\u00f3n cat\u00f3lica, pero durante varios a\u00f1os se hab\u00edan estado reuniendo para estudiar y discutir la Biblia con su mentor, Ulrico Zuinglio, sacerdote de la iglesia principal de la ciudad (Grossm\u00fcnster).<\/p>\n<p>Al leer las Escrituras, el grupo comenz\u00f3 a cuestionar varias pr\u00e1cticas de la Iglesia Cat\u00f3lica, incluido el bautismo de infantes, aunque quienes participaban ten\u00edan distintas opiniones acerca de qu\u00e9 hacer al respecto. Zuinglio, apoyado por el Ayuntamiento de Z\u00farich, insist\u00eda en realizar reformas moderadas e introducirlas gradualmente. Los miembros del grupo de estudio b\u00edblico se resist\u00edan. Argumentaban que si las Escrituras eran claras, los cambios en la pr\u00e1ctica de la iglesia deb\u00edan realizarse de inmediato, independientemente de las consecuencias pol\u00edticas o sociales.<\/p>\n<p>Por tanto, ese d\u00eda de enero de 1525, el peque\u00f1o grupo renunci\u00f3 formalmente a su bautismo de infantes y, siguiendo el modelo de Jes\u00fas y Juan el Bautista, recibi\u00f3 el bautismo de adultos como s\u00edmbolo de su compromiso voluntario de seguir a Cristo y de apoyarse mutuamente en esta nueva etapa de fe.<\/p>\n<p>Para los cristianos modernos, dicha acci\u00f3n parece casi trivial. Despu\u00e9s de todo, \u00bfcu\u00e1n problem\u00e1tico pod\u00eda ser el hecho de que un grupo de personas se reuniera a orar para luego verter agua sobre sus cabezas? Sin embargo, esta acci\u00f3n \u2013que marc\u00f3 el comienzo del movimiento anabautista (o \u201crebautizador\u201d)\u2013 tuvo profundas consecuencias. A los pocos d\u00edas, el Ayuntamiento de Z\u00farich orden\u00f3 el arresto y encarcelamiento de cualquiera que participara en tales bautismos. Hacia 1526, las autoridades declararon el bautismo de adultos un delito capital. Y en enero de 1527, F\u00e9lix Manz, en cuya casa se hab\u00eda reunido el grupo, sufri\u00f3 la consecuencia final de sus convicciones. Con las manos y los pies atados a un poste de madera, Manz fue \u201cbautizado\u201d una vez m\u00e1s, empujado a las g\u00e9lidas aguas del r\u00edo Limmat en una ejecuci\u00f3n p\u00fablica.<\/p>\n<p>A medida que se extend\u00eda el movimiento anabautista, los l\u00edderes pol\u00edticos y eclesiales los condenaron como herejes. Durante las siguientes d\u00e9cadas, unos tres mil creyentes fueron ejecutados por el delito de ser \u201canabautistas\u201d o \u201crebautizadores\u201d.<\/p>\n<p>Sin embargo, el movimiento que iniciaron sigue vivo. Actualmente, unos 2,2 millones de cristianos en todo el mundo&nbsp;se definen como parte de la tradici\u00f3n anabautista, incluidas las 107 iglesias nacionales miembros que conforman el Congreso Mundial Menonita<\/p>\n<p>Los ingredientes parecen bastante sencillos: agua, una reuni\u00f3n de testigos y algunas palabras elegidas cuidadosamente. Para una persona laica que mira desde afuera, le puede parecer dif\u00edcil entender por qu\u00e9 la pr\u00e1ctica cristiana del bautismo es tan importante. Pero, a pesar de su sencillez, pr\u00e1cticamente todos los grupos cristianos consideran el bautismo un acontecimiento fundacional, un ritual que expresa convicciones b\u00e1sicas de su fe.<\/p>\n<p>Pocas pr\u00e1cticas son tan fundamentales para la iglesia cristiana y, sin embargo, pocas han sido la fuente de tantos desacuerdos y debates entre cristianos.<\/p>\n<ul>\n<li>\u00bfEs el bautismo esencial para la salvaci\u00f3n?<\/li>\n<li>\u00bfCu\u00e1l es la edad apropiada para el bautismo?<\/li>\n<li>\u00bfC\u00f3mo se deber\u00eda realizar el ritual?<\/li>\n<li>\u00bfEl bautismo confiere salvaci\u00f3n en s\u00ed mismo o es un s\u00edmbolo de la salvaci\u00f3n ya recibida?<\/li>\n<\/ul>\n<h3>El bautismo en la tradici\u00f3n cristiana<\/h3>\n<figure class=\"image\" style=\"float:right\"><img decoding=\"async\" alt=\"\" height=\"200\" data-src=\"\/sites\/default\/files\/website_files_2020\/2020-01-21-dr-baptism-2.jpg\" width=\"356\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 356px; --smush-placeholder-aspect-ratio: 356\/200;\" \/><figcaption>Foto: Mariano Ram\u00edrez<\/figcaption><\/figure>\n<p>Las ra\u00edces del bautismo cristiano se inspiran en las im\u00e1genes b\u00edblicas del agua, un s\u00edmbolo perdurable de purificaci\u00f3n, renovaci\u00f3n y de la vida misma. En el Antiguo Testamento, el agua a menudo se asocia con la presencia sanadora de Dios: un manantial en el desierto, un pozo vivificante o la justicia que fluye \u201ccomo un r\u00edo impetuoso\u201d.<\/p>\n<p>El s\u00edmbolo del bautismo cristiano proviene directamente de la historia del \u00c9xodo del Antiguo Testamento, cuando Dios dividi\u00f3 las aguas del Mar Rojo para permitir que los hijos de Israel huyeran de la esclavitud en Egipto y escaparan de los ej\u00e9rcitos del Fara\u00f3n. Esta dram\u00e1tica acci\u00f3n de \u201ccruzar las aguas\u201d se\u00f1al\u00f3 el renacimiento de los hijos de Israel. Habiendo cruzado las aguas, ya no eran esclavos, se hab\u00edan convertido en la nueva comunidad del pueblo de Dios, comprometidos mutuamente por el don de la Ley y por su dependencia de Dios como gu\u00eda y sustento.<\/p>\n<p>Resuenan claramente los ecos de la historia del \u00c9xodo en el relato de Juan en el Nuevo Testamento, a quien apodaron \u201cEl Bautista\u201d. La ardiente predicaci\u00f3n de Juan llam\u00f3 al arrepentimiento: la transformaci\u00f3n del coraz\u00f3n simbolizada por un rito de purificaci\u00f3n en las aguas del r\u00edo Jord\u00e1n. Seg\u00fan los evangelios, Jes\u00fas comenz\u00f3 su ministerio formal solo despu\u00e9s de haber sido bautizado por Juan. Esa acci\u00f3n, acompa\u00f1ada por la bendici\u00f3n de Dios y la clara presencia del Esp\u00edritu Santo, signific\u00f3 para Jes\u00fas un \u201ccruce\u201d hacia un nuevo ministerio de sanaci\u00f3n y ense\u00f1anza que culmin\u00f3 tres a\u00f1os despu\u00e9s con su crucifixi\u00f3n, muerte y resurrecci\u00f3n.<\/p>\n<p>Los primeros cristianos entend\u00edan el bautismo como un s\u00edmbolo pleno de significado, proveniente tanto del Antiguo Testamento como de la vida de Jes\u00fas. Como el \u00c9xodo, el bautismo en la iglesia primitiva simbolizaba la renuncia a una vida esclavizada por el pecado y un \u201ccruce\u201d hacia una nueva identidad como parte de una comunidad de creyentes que, como los Hijos de Israel, estaban comprometidos a vivir en dependencia de Dios.<\/p>\n<p>Muchos de los primeros cristianos tambi\u00e9n consideraban el bautismo una representaci\u00f3n de la muerte y resurrecci\u00f3n de Cristo. Los candidatos al bautismo entraban al agua desnudos, despojados y vulnerables, como Cristo en la cruz, neg\u00e1ndose a s\u00ed mismos. Despu\u00e9s de salir del agua, se vest\u00edan con t\u00fanicas blancas como s\u00edmbolo de la resurrecci\u00f3n y de su nueva identidad como seguidores de Jes\u00fas<\/p>\n<p>Existe fuerte evidencia del siglo II y III que sugiere que los primeros cristianos bautizaban solo a adultos; y solamente tras un largo y riguroso per\u00edodo de instrucci\u00f3n y capacitaci\u00f3n. Es decir, la iglesia primitiva reservaba el bautismo para aquellos que hab\u00edan experimentado una transformaci\u00f3n del coraz\u00f3n, que estaban comprometidos con una vida de discipulado diario, y estaban dispuestos a formar parte de una nueva comunidad de creyentes.<\/p>\n<h3>Del bautismo voluntario al bautismo de infantes<\/h3>\n<p>Sin embargo, en alg\u00fan momento durante el siglo IV, esta pr\u00e1ctica comenz\u00f3 a cambiar. Un elemento fundamental de este cambio en la pr\u00e1ctica bautismal fue la conversi\u00f3n del emperador romano Constantino en el 312 d.C., un acontecimiento que transform\u00f3 lentamente la naturaleza misma de la iglesia cristiana. Durante el siglo posterior a la conversi\u00f3n de Constantino, la iglesia pas\u00f3 de ser una peque\u00f1a minor\u00eda perseguida, a convertirse en una poderosa instituci\u00f3n cuyos obispos llegaron a depender de los ej\u00e9rcitos del imperio romano para su protecci\u00f3n y como medio para eliminar la herej\u00eda.<\/p>\n<p>Gradualmente, el cristianismo se convirti\u00f3 en la religi\u00f3n \u201coficial\u201d de los emperadores romanos, una especie de \u201cpegamento\u201d religioso-cultural que pod\u00eda ayudar a unir un imperio que se estaba fragmentando.<\/p>\n<p>Dado que todos en el territorio ahora estaban obligados a ser cristianos, ya no ten\u00eda sentido asociar el bautismo con el arrepentimiento, con una transformaci\u00f3n de vida, o con una nueva identidad en una comunidad de creyentes.<\/p>\n<p>Casi al mismo tiempo, surgieron nuevos argumentos para defender la pr\u00e1ctica del bautismo de infantes. Por ejemplo, a fines del siglo IV, San Agust\u00edn (354-430) insisti\u00f3 en que desde el mismo momento del nacimiento, los seres humanos estaban atrapados en la esclavitud del pecado. El bautismo de infantes, argument\u00f3, era necesario para la salvaci\u00f3n del alma del ni\u00f1o. En su ense\u00f1anza dec\u00eda que el propio acto del bautismo confer\u00eda al ni\u00f1o el don espiritual de la gracia. El sacramento del bautismo incorporaba al ni\u00f1o a la iglesia, salvando su alma de la mancha del pecado original y de las garras del infierno.<\/p>\n<p>En la sociedad medieval posterior, el bautismo tambi\u00e9n implicaba la membres\u00eda del ni\u00f1o en la comunidad c\u00edvica, y se registraba como un sujeto que alg\u00fan d\u00eda pagar\u00eda impuestos y le deb\u00eda lealtad al se\u00f1or feudal local.<\/p>\n<p>Los l\u00edderes de la Reforma, Lutero, Zuinglio, Calvino y otros, acordaron que los ni\u00f1os deb\u00edan ser bautizados al nacer. Lutero argument\u00f3 que el bautismo de infantes confirmaba que \u00e9ramos totalmente dependientes del don gratuito de la gracia de Dios para nuestra salvaci\u00f3n, no de nuestras propias acciones. Zuinglio se\u00f1al\u00f3 que Jes\u00fas ense\u00f1\u00f3 que debemos volvernos \u201ccomo ni\u00f1os\u201d para entrar en el Reino de Dios. El bautismo de infantes, como la circuncisi\u00f3n para los jud\u00edos del Antiguo Testamento, era una se\u00f1al de inclusi\u00f3n en el cuerpo de creyentes y un compromiso por parte de los creyentes de criar a ese ni\u00f1o en los caminos de Dios.<\/p>\n<h3>Interpretaci\u00f3n anabautistamenonita del bautismo<\/h3>\n<p>Cuando los l\u00edderes anabautistas comenzaron a desafiar la pr\u00e1ctica del bautismo de infantes, la gente reaccion\u00f3 con confusi\u00f3n, enojo y finalmente con violencia.<\/p>\n<p>Para los anabautistas, el argumento principal a favor del bautismo de los creyentes, a diferencia del bautismo de infantes, se basa en un principio fundamental de la Reforma misma: \u201cSolo la Escritura basta\u201d. En su lectura del Nuevo Testamento, los anabautistas del siglo XVI no pudieron encontrar ninguna justificaci\u00f3n b\u00edblica para la pr\u00e1ctica de bautizar beb\u00e9s. En cambio, las ense\u00f1anzas de Jes\u00fas vinculaban expl\u00edcitamente el bautismo con el arrepentimiento y la fe, algo que un ni\u00f1o claramente no pod\u00eda hacer. Por ejemplo, mientras instru\u00eda a los disc\u00edpulos que predicaran las buenas nuevas del evangelio, Jes\u00fas prometi\u00f3: \u201cTodo el que crea y sea bautizado, ser\u00e1 salvo\u201d (Marcos 16,16). La secuencia aqu\u00ed es clara: la fe viene primero, luego el bautismo.<\/p>\n<p>Al final de su ministerio, en una amonestaci\u00f3n final a los disc\u00edpulos, Jes\u00fas volvi\u00f3 a hablar del bautismo. \u201cPor tanto, vayan\u201d, les dijo a los disc\u00edpulos en Mateo 28,19-20, \u201cy hagan disc\u00edpulos de todas las naciones, bautiz\u00e1ndolos en el nombre del Padre y del Hijo y del Esp\u00edritu Santo, y ense\u00f1\u00e1ndoles a obedecer todo lo que yo les he mandado\u201d.<\/p>\n<p>Aqu\u00ed nuevamente, el orden es importante. Jes\u00fas exig\u00eda a sus seguidores que primero \u201chicieran disc\u00edpulos\u201d y luego que bautizaran, con la expectativa de que a los nuevos conversos tambi\u00e9n se les ense\u00f1ar\u00eda a obedecer los mandamientos de Cristo. Por tanto, las personas se convierten en seguidores de Jes\u00fas al escuchar, comprender y responder a un llamado, tal como lo hab\u00edan hecho los primeros disc\u00edpulos.<\/p>\n<p>Esta misma secuencia se repite en la historia de los primeros bautismos de la iglesia apost\u00f3lica, como se registra en Hechos 2. La historia comienza con Pedro predicando un serm\u00f3n a una multitud de jud\u00edos, que se ha reunido en Jerusal\u00e9n para la celebraci\u00f3n anual de la Pascua. Pedro termina su serm\u00f3n con un llamado al arrepentimiento. \u201cLos que aceptaron su mensaje\u201d, concluye el relato, \u201cfueron bautizados\u201d.<\/p>\n<p>Para los anabautistas, y los grupos que los siguieron, el compromiso de seguir a Jes\u00fas implicaba una conversi\u00f3n o un \u201ccambio\u201d. Es decir, una reorientaci\u00f3n radical de prioridades, simbolizada por el bautismo, que pod\u00eda llevar a la persecuci\u00f3n e incluso a la muerte. \u00ac\u00b0No es una decisi\u00f3n que pueda tomar un ni\u00f1o!<\/p>\n<h3>El significado del bautismo: un cord\u00f3n de tres hilos<\/h3>\n<figure class=\"image\" style=\"float:right\"><img decoding=\"async\" alt=\"\" height=\"250\" data-src=\"\/sites\/default\/files\/website_files_2020\/20210314_pastornguyenminhsang_w_nguyenthilien_mennonitehoianchurch.jpg\" width=\"228\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 228px; --smush-placeholder-aspect-ratio: 228\/250;\" \/><figcaption>El pastor Sang Nguyen Minh<br \/>\nbautiza a Nguyen Thi Lien en Vietnam.<br \/>\nFoto: Iglesia Menonita de Hoi An<\/figcaption><\/figure>\n<p>Los anabautistas no cre\u00edan que el acto del bautismo, en s\u00ed mismo, convirtiera a una persona en cristiana. M\u00e1s bien, el bautismo era una \u201cse\u00f1al\u201d externa o un \u201cs\u00edmbolo\u201d de una transformaci\u00f3n interna.<\/p>\n<p>Los s\u00edmbolos, por supuesto, pueden tener m\u00e1s de un significado. Bas\u00e1ndose en un vers\u00edculo de 1 Juan 5, los anabautistas describ\u00edan frecuentemente el bautismo como un cord\u00f3n de tres hilos: esp\u00edritu, agua y sangre, y todos apuntaban a las cualidades esenciales del bautismo:<\/p>\n<p>Los hijos de Dios son aquellos que creen que Jes\u00fas es el Cristo y siguen sus mandamientos. Seg\u00fan 1 Juan, tres son los que dan testimonio de que Jes\u00fas es el Hijo de Dios: \u201cel Esp\u00edritu, el agua y la sangre; y los tres concuerdan\u201d (1 Juan 5,8).<\/p>\n<p>1.&nbsp;. En su nivel m\u00e1s b\u00e1sico, el bautismo es un signo visible de la obra transformadora del Esp\u00edritu Santo. Es un reconocimiento p\u00fablico de que el creyente se ha arrepentido del pecado, ha aceptado el perd\u00f3n de Dios y ha \u201centregado su vida a Cristo\u201d. El bautismo celebra el don de la salvaci\u00f3n: el don de la gracia bondadosa, misericordiosa y propiciadora de Dios.<\/p>\n<p>2.&nbsp;Al mismo tiempo, el bautismo es tambi\u00e9n una se\u00f1al de pertenencia a una nueva comunidad. En el bautismo de agua nos sometemos al cuidado, a la disciplina y hermandad de la comunidad. En el bautismo prometemos dar y recibir consejo, compartir nuestras posesiones y servir en la misi\u00f3n m\u00e1s amplia de la iglesia. En la tradici\u00f3n anabautistamenonita la salvaci\u00f3n nunca es puramente privada o hacia dentro; nuestra fe siempre se expresa en nuestras relaciones con los dem\u00e1s.<\/p>\n<p>3.&nbsp;Finalmente, en el bautismo los nuevos creyentes prometen seguir el camino de Jes\u00fas, vivir como \u00e9l vivi\u00f3 y ense\u00f1\u00f3, aunque incluya \u201a\u00c4\u00eecomo sucedi\u00f3 con Jes\u00fas\u201a\u00c4\u00ee malentendidos, persecuci\u00f3n, sufrimiento o incluso la muerte. No es suficiente afirmar el perd\u00f3n de los pecados o que tu nombre figure en una lista de miembros de la iglesia. El bautismo tambi\u00e9n implica una manera de vivir que se parezca a la de Jes\u00fas: una manera de vivir que ame a Dios de todo coraz\u00f3n y al semejante como a s\u00ed mismo. Los anabautistas del siglo XVI procuraron recuperar estas ense\u00f1anzas, que hab\u00edan perdido claridad en la historia de la iglesia. Bas\u00e1ndose en los conceptos b\u00edblicos, entendieron el bautismo como una se\u00f1al de la presencia transformadora del Esp\u00edritu, como un s\u00edmbolo de la pertenencia a una comunidad, y de la disposici\u00f3n a seguir a Cristo incluso a costa de grandes sacrificios.<\/p>\n<p>Los anabautistas del siglo XVI procuraron recuperar estas ense\u00f1anzas, que hab\u00edan perdido claridad en la historia de la iglesia. Bas\u00e1ndose en los conceptos b\u00edblicos, entendieron el bautismo como una se\u00f1al de la presencia transformadora del Esp\u00edritu, como un s\u00edmbolo de la pertenencia a una comunidad, y de la disposici\u00f3n a seguir a Cristo incluso a costa de grandes sacrificios.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<table style=\"width:100%\">\n<tbody>\n<tr>\n<td style=\"width:235px\">\n<p style=\"text-align:center\"><img decoding=\"async\" alt=\"\" height=\"164\" data-src=\"\/sites\/default\/files\/website_files_2020\/john_roth_2019_goshencollege_0.jpg\" width=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/164;\" \/><\/p>\n<\/td>\n<td style=\"width:813px\">John Roth, secretario de la Comisi\u00f3n de Fe y Vida y profesor de historia de Goshen College, es miembro de la Iglesia Menonita de Berkey Avenue, Goshen, Indiana, EE. UU.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<hr \/>\n<p><a href=\"\/es\/node\/4134\">Este art\u00edculo apareci\u00f3 por primera vez en&nbsp;<em>Correo\/Courier\/Courrier&nbsp;<\/em>en octubre de 2021.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras un di\u00e1logo de cinco a\u00f1os con te\u00f3logos de las tradiciones cat\u00f3lica romana y luterana, el Comit\u00e9 de Fe y Vida invit\u00f3 a los miembros del Congreso Mundial Menonita a considerar juntos nuestras pr\u00e1cticas anabautistas en Renovaci\u00f3n 2027, en dos seminarios web titulados, \u201cCrean y sean bautizados: Un di\u00e1logo mundial sobre el bautismo\u201d. Contexto b\u00edblico, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":94252,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"network":[1306],"eventcategory":[],"class_list":["post-9151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","network-courier-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cCrean y sean bautizados: Un di\u00e1logo mundial sobre el bautismo\u201d - Mennonite World Conference<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cCrean y sean bautizados: Un di\u00e1logo mundial sobre el bautismo\u201d - Mennonite World Conference\" \/>\n<meta property=\"og:description\" content=\"Tras un di\u00e1logo de cinco a\u00f1os con te\u00f3logos de las tradiciones cat\u00f3lica romana y luterana, el Comit\u00e9 de Fe y Vida invit\u00f3 a los miembros del Congreso Mundial Menonita a considerar juntos nuestras pr\u00e1cticas anabautistas en Renovaci\u00f3n 2027, en dos seminarios web titulados, \u201cCrean y sean bautizados: Un di\u00e1logo mundial sobre el bautismo\u201d. Contexto b\u00edblico, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Mennonite World Conference\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MennoniteWorldConference\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-22T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-10T18:03:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/baptism_1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mennworldcon\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\\\/\"},\"author\":{\"name\":\"mennworldcon\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/person\\\/11f6ae0d7d1868ba20a1cc27f067c836\"},\"headline\":\"\u201cCrean y sean bautizados: Un di\u00e1logo mundial sobre el bautismo\u201d\",\"datePublished\":\"2021-11-22T00:00:00+00:00\",\"dateModified\":\"2024-12-10T18:03:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\\\/\"},\"wordCount\":2660,\"publisher\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/baptism_1-scaled.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\\\/\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\\\/\",\"name\":\"\u201cCrean y sean bautizados: Un di\u00e1logo mundial sobre el bautismo\u201d - Mennonite World Conference\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/baptism_1-scaled.jpg\",\"datePublished\":\"2021-11-22T00:00:00+00:00\",\"dateModified\":\"2024-12-10T18:03:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/baptism_1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/baptism_1-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cCrean y sean bautizados: Un di\u00e1logo mundial sobre el bautismo\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/\",\"name\":\"Mennonite World Conference\",\"description\":\"A communion of Anabaptist-related churches\",\"publisher\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\"},\"alternateName\":\"MWC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\",\"name\":\"Mennonite World Conference\",\"alternateName\":\"MWC\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/MWC_Sig_Blue_Horiz_webheader1-logo.svg\",\"contentUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/MWC_Sig_Blue_Horiz_webheader1-logo.svg\",\"width\":786,\"height\":82,\"caption\":\"Mennonite World Conference\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MennoniteWorldConference\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mennonite-world-conference-mwc\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mwcmm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/mwccmm\",\"https:\\\/\\\/bsky.app\\\/profile\\\/mwcmm.bsky.social\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/person\\\/11f6ae0d7d1868ba20a1cc27f067c836\",\"name\":\"mennworldcon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g\",\"caption\":\"mennworldcon\"},\"sameAs\":[\"https:\\\/\\\/mwc-cmm.org\"],\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/author\\\/mennworldcon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cCrean y sean bautizados: Un di\u00e1logo mundial sobre el bautismo\u201d - Mennonite World Conference","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cCrean y sean bautizados: Un di\u00e1logo mundial sobre el bautismo\u201d - Mennonite World Conference","og_description":"Tras un di\u00e1logo de cinco a\u00f1os con te\u00f3logos de las tradiciones cat\u00f3lica romana y luterana, el Comit\u00e9 de Fe y Vida invit\u00f3 a los miembros del Congreso Mundial Menonita a considerar juntos nuestras pr\u00e1cticas anabautistas en Renovaci\u00f3n 2027, en dos seminarios web titulados, \u201cCrean y sean bautizados: Un di\u00e1logo mundial sobre el bautismo\u201d. Contexto b\u00edblico, [&hellip;]","og_url":"https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/","og_site_name":"Mennonite World Conference","article_publisher":"https:\/\/www.facebook.com\/MennoniteWorldConference","article_published_time":"2021-11-22T00:00:00+00:00","article_modified_time":"2024-12-10T18:03:59+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/baptism_1-scaled.jpg","type":"image\/jpeg"}],"author":"mennworldcon","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/#article","isPartOf":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/"},"author":{"name":"mennworldcon","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/person\/11f6ae0d7d1868ba20a1cc27f067c836"},"headline":"\u201cCrean y sean bautizados: Un di\u00e1logo mundial sobre el bautismo\u201d","datePublished":"2021-11-22T00:00:00+00:00","dateModified":"2024-12-10T18:03:59+00:00","mainEntityOfPage":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/"},"wordCount":2660,"publisher":{"@id":"https:\/\/mwc-cmm.org\/en\/#organization"},"image":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/#primaryimage"},"thumbnailUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/baptism_1-scaled.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/","url":"https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/","name":"\u201cCrean y sean bautizados: Un di\u00e1logo mundial sobre el bautismo\u201d - Mennonite World Conference","isPartOf":{"@id":"https:\/\/mwc-cmm.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/#primaryimage"},"image":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/#primaryimage"},"thumbnailUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/baptism_1-scaled.jpg","datePublished":"2021-11-22T00:00:00+00:00","dateModified":"2024-12-10T18:03:59+00:00","breadcrumb":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/#primaryimage","url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/baptism_1-scaled.jpg","contentUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/baptism_1-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/mwc-cmm.org\/es\/stories\/crean-y-sean-bautizados-un-dialogo-mundial-sobre-el-bautismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mwc-cmm.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u201cCrean y sean bautizados: Un di\u00e1logo mundial sobre el bautismo\u201d"}]},{"@type":"WebSite","@id":"https:\/\/mwc-cmm.org\/en\/#website","url":"https:\/\/mwc-cmm.org\/en\/","name":"Mennonite World Conference","description":"A communion of Anabaptist-related churches","publisher":{"@id":"https:\/\/mwc-cmm.org\/en\/#organization"},"alternateName":"MWC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mwc-cmm.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mwc-cmm.org\/en\/#organization","name":"Mennonite World Conference","alternateName":"MWC","url":"https:\/\/mwc-cmm.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2026\/01\/MWC_Sig_Blue_Horiz_webheader1-logo.svg","contentUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2026\/01\/MWC_Sig_Blue_Horiz_webheader1-logo.svg","width":786,"height":82,"caption":"Mennonite World Conference"},"image":{"@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MennoniteWorldConference","https:\/\/www.linkedin.com\/company\/mennonite-world-conference-mwc\/","https:\/\/www.instagram.com\/mwcmm\/","https:\/\/www.youtube.com\/user\/mwccmm","https:\/\/bsky.app\/profile\/mwcmm.bsky.social"]},{"@type":"Person","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/person\/11f6ae0d7d1868ba20a1cc27f067c836","name":"mennworldcon","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g","caption":"mennworldcon"},"sameAs":["https:\/\/mwc-cmm.org"],"url":"https:\/\/mwc-cmm.org\/es\/stories\/author\/mennworldcon\/"}]}},"_links":{"self":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/posts\/9151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/comments?post=9151"}],"version-history":[{"count":0,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/posts\/9151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/media\/94252"}],"wp:attachment":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/media?parent=9151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/categories?post=9151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/tags?post=9151"},{"taxonomy":"network","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/network?post=9151"},{"taxonomy":"eventcategory","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/eventcategory?post=9151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}