{"id":8675,"date":"2016-12-19T00:00:00","date_gmt":"2016-12-19T00:00:00","guid":{"rendered":"https:\/\/mwc-cmm.org\/your-light-is-needed-3\/"},"modified":"2024-12-10T18:00:25","modified_gmt":"2024-12-10T18:00:25","slug":"your-light-is-needed-3","status":"publish","type":"post","link":"https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/","title":{"rendered":"Se necesita su luz"},"content":{"rendered":"<p>&nbsp;<\/p>\n<hr \/>\n<p><em>As\u00ed como las partes del coraz\u00f3n, las cuatro comisiones del CMM sirven a la comunidad mundial de iglesias afines al anabautismo, en las \u00e1reas de diaconado, fe y vida, paz y misiones. Las comisiones preparan materiales para la consideraci\u00f3n del Concilio General, brindan gu\u00eda y proponen recursos a las iglesias miembros, adem\u00e1s, propician redes y compa\u00f1erismo en relaci\u00f3n al CMM trabajando juntos en temas de inter\u00e9s y enfoque com\u00fan. A continuaci\u00f3n, una de las comisiones comparte un mensaje de la perspectiva de su ministerio.<\/em><\/p>\n<hr \/>\n<p>\u201cSi un miembro del cuerpo sufre, todos los dem\u00e1s sufren tambi\u00e9n; y si un miembro recibe atenci\u00f3n especial, todos los dem\u00e1s comparten su alegr\u00eda\u201d (1 Corintios 12,26).<\/p>\n<p>\u201cEsta visita me hizo comprender que somos parte de una gran familia mundial. \u00a1Ahora sabemos que no estamos solos!\u201d<\/p>\n<p>Esto fue lo que o\u00edmos cuando una delegaci\u00f3n de las Comisiones de Paz y de Di\u00e1conos del Congreso Mundial Menonita visit\u00f3 las iglesias Hermanos Menonitas en Panam\u00e1. Cuando vive con desaf\u00edos que amenazan la manera tradicional de vivir, \u00bfqu\u00e9 es m\u00e1s importante que saber que no est\u00e1 solo? El saber que hay hermanos y hermanas que est\u00e1n orando \u2013 aunque no lo conozcan personalmente \u2013 puede ser la diferencia entre rendirse o continuar esperanzado, confiando en el Se\u00f1or.<\/p>\n<p>\u201cNo les pedimos que resuelvan nuestros problemas. Todo lo que pedimos es contar nuestra historia y orar por nosotros.\u201d<\/p>\n<p>Ser un di\u00e1cono dentro del CMM no se trata de dar ayuda financiera o crear programas de ayuda. Los di\u00e1conos caminan junto a las iglesias, escuchan, comparten y oran con ellas en tiempos de angustia o de alegr\u00eda. A veces nos sentimos tan impotentes para prestar ayuda, pero no debemos subestimar el poder de caminar juntos, de escuchar y de orar.&nbsp;<\/p>\n<table>\n<tbody>\n<tr>\n<td><em style=\"text-align:center\"><img decoding=\"async\" alt=\"\" data-src=\"\/sites\/default\/files\/website_files\/panama_praying_together_for_a_sick_child_v1.jpg\" style=\"width:300px; height:176px; margin:10px; float:right\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/em><\/p>\n<div style=\"text-align:center\"><span style=\"font-size:11px\">Miembros de la iglesia oran por un ni\u00f1o<\/span><\/div>\n<div style=\"text-align:center\"><span style=\"font-size:11px\">&nbsp; &nbsp; enfermo en Panam\u00e1. Foto: Henk Stenvers<\/span>.&nbsp;<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\u201cLa Comisi\u00f3n de Di\u00e1conos debe ser la mano c\u00e1lida de la iglesia mundial.\u201d En 2009, Danisa Ndlovu, el entonces presidente del CMM, dijo estas palabras en la primera reuni\u00f3n de la comisi\u00f3n en Paraguay. Una mano sobre el hombro, que muestra que otros se preocupan, sentir el calor de la unidad con otros que comparten las mismas convicciones. A pesar de que vivimos en situaciones tan diferentes, expresamos nuestra fe de formas tan distintas y tenemos diversas historias, sabemos que estamos unidos en nuestra fe. En nuestro deseo de seguir a Cristo, somos parte de un solo cuerpo.<\/p>\n<p>El Fondo de Ayuda de la Iglesia Mundial puede apoyar a las iglesias en el Sur global para realizar proyectos que permitan promoverla vida y la misi\u00f3n de la iglesia. Puede ser muy importante para una iglesia local tener su propio lugar para los cultos o construir una escuela. El significado de reconstruir despu\u00e9s de una destrucci\u00f3n causada por un desastre o por la violencia, sobrepasa la imaginaci\u00f3n. Se trata de ser una comunidad \u2013 local y mundial.<\/p>\n<p>Y al igual que Pablo les escribe a los Corintios, las partes del cuerpo est\u00e1n unidas, a\u00fan si son diferentes. Son interdependientes; si falta una, est\u00e1 incompleto (1 Corintios 12:14\u201325).<\/p>\n<p>La comunidad mundial es como la iglesia en Pimpimsu en Ghana. Visitamos la peque\u00f1a iglesia al atardecer, despu\u00e9s de que ya hab\u00eda oscurecido. Las personas vinieron a la iglesia una a una a darnos la bienvenida y todos tra\u00edan una luz. Cada vez que entraba alguien, la iglesia se iluminaba mejor. Cuando la iglesia se llen\u00f3, hab\u00eda una luz brillante debido a todas las peque\u00f1as l\u00e1mparas.<\/p>\n<p>Eso es ser comunidad, de eso se trata. Cuando usted no est\u00e1 aqu\u00ed, la iglesia est\u00e1 un poco m\u00e1s oscura. Ya sea que estemos presentes en las asambleas o en esp\u00edritu en oraci\u00f3n, podemos ser testigos del maravilloso mensaje de paz que Cristo nos dio. \u00a1Si usted no est\u00e1 all\u00ed, es extra\u00f1ado, porque la luz es menos clara!<\/p>\n<p>La Comisi\u00f3n de Di\u00e1conos quiere ser una herramienta para apoyar y fortalecer esa comunidad global. \u00danase a nosotros para caminar junto a nuestra familia anabautista mundial a trav\u00e9s de la Red de Oraci\u00f3n del CMM. *<\/p>\n<p><em>\u2014Henk Stenvers es secretario de la Comisi\u00f3n de Di\u00e1conos del CMM.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>*En 2016, la Comisi\u00f3n de Di\u00e1conos lanz\u00f3 nuevamente una red de oraci\u00f3n basada en correos electr\u00f3nicos, tras el \u00e9xito de la iniciativa de oraci\u00f3n en la Asamblea 16. La Red de Oraci\u00f3n env\u00eda un correo electr\u00f3nico cada dos meses que contendr\u00e1 de cuatro a cinco oraciones. Es posible que tambi\u00e9n haya correos adicionales cuando surja un llamado de oraci\u00f3n urgente. Los correos electr\u00f3nicos est\u00e1n disponibles en ingl\u00e9s, espa\u00f1ol o franc\u00e9s. Si le gustar\u00eda compartir un motivo de oraci\u00f3n con nosotros, por favor escriba a <a href=\"mailto:oraciones@mwc-cmm.org\">oraciones@mwc-cmm.org<\/a>.<\/p>\n<p>\u00bfLe gusta lo que est\u00e1 leyendo? \u00bfSab\u00eda que usted puede apoyar la labor del CMM escribiendo, recolectando o compartiendo historias de anabautistas de todo el mundo? <a href=\"https:\/\/www.mwc-cmm.org\/article\/maneras-de-donar\">Haga clic aqu\u00ed para hacer una donaci\u00f3n.<\/a><\/p>\n<p>&nbsp;<\/p>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; As\u00ed como las partes del coraz\u00f3n, las cuatro comisiones del CMM sirven a la comunidad mundial de iglesias afines al anabautismo, en las \u00e1reas de diaconado, fe y vida, paz y misiones. Las comisiones preparan materiales para la consideraci\u00f3n del Concilio General, brindan gu\u00eda y proponen recursos a las iglesias miembros, adem\u00e1s, propician redes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":88384,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[547],"tags":[483,1058,211,822],"network":[1261],"eventcategory":[],"class_list":["post-8675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-de-nuestros-lideres","tag-comision-de-diaconos","tag-comision-de-paz","tag-deacons-commission","tag-henk-stenvers-es","network-deacons-commission-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se necesita su luz - Mennonite World Conference<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se necesita su luz - Mennonite World Conference\" \/>\n<meta property=\"og:description\" content=\"&nbsp; As\u00ed como las partes del coraz\u00f3n, las cuatro comisiones del CMM sirven a la comunidad mundial de iglesias afines al anabautismo, en las \u00e1reas de diaconado, fe y vida, paz y misiones. Las comisiones preparan materiales para la consideraci\u00f3n del Concilio General, brindan gu\u00eda y proponen recursos a las iglesias miembros, adem\u00e1s, propician redes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Mennonite World Conference\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MennoniteWorldConference\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-19T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-10T18:00:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/2-ghana_26-11_v1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1689\" \/>\n\t<meta property=\"og:image:height\" content=\"1392\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mennworldcon\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/your-light-is-needed-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/your-light-is-needed-3\\\/\"},\"author\":{\"name\":\"mennworldcon\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/person\\\/11f6ae0d7d1868ba20a1cc27f067c836\"},\"headline\":\"Se necesita su luz\",\"datePublished\":\"2016-12-19T00:00:00+00:00\",\"dateModified\":\"2024-12-10T18:00:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/your-light-is-needed-3\\\/\"},\"wordCount\":872,\"publisher\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/your-light-is-needed-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/2-ghana_26-11_v1.jpg\",\"keywords\":[\"Comisi\u00f3n de Di\u00e1conos\",\"Comisi\u00f3n de Paz\",\"Deacons Commission\",\"Henk Stenvers\"],\"articleSection\":[\"De Nuestros L\u00edderes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/your-light-is-needed-3\\\/\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/your-light-is-needed-3\\\/\",\"name\":\"Se necesita su luz - Mennonite World Conference\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/your-light-is-needed-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/your-light-is-needed-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/2-ghana_26-11_v1.jpg\",\"datePublished\":\"2016-12-19T00:00:00+00:00\",\"dateModified\":\"2024-12-10T18:00:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/your-light-is-needed-3\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/your-light-is-needed-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/your-light-is-needed-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/2-ghana_26-11_v1.jpg\",\"contentUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/2-ghana_26-11_v1.jpg\",\"width\":1689,\"height\":1392},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/your-light-is-needed-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se necesita su luz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/\",\"name\":\"Mennonite World Conference\",\"description\":\"A communion of Anabaptist-related churches\",\"publisher\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\"},\"alternateName\":\"MWC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\",\"name\":\"Mennonite World Conference\",\"alternateName\":\"MWC\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/MWC_Sig_Blue_Horiz_webheader1-logo.svg\",\"contentUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/MWC_Sig_Blue_Horiz_webheader1-logo.svg\",\"width\":786,\"height\":82,\"caption\":\"Mennonite World Conference\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MennoniteWorldConference\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mennonite-world-conference-mwc\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mwcmm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/mwccmm\",\"https:\\\/\\\/bsky.app\\\/profile\\\/mwcmm.bsky.social\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/person\\\/11f6ae0d7d1868ba20a1cc27f067c836\",\"name\":\"mennworldcon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g\",\"caption\":\"mennworldcon\"},\"sameAs\":[\"https:\\\/\\\/mwc-cmm.org\"],\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/author\\\/mennworldcon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se necesita su luz - Mennonite World Conference","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/","og_locale":"es_ES","og_type":"article","og_title":"Se necesita su luz - Mennonite World Conference","og_description":"&nbsp; As\u00ed como las partes del coraz\u00f3n, las cuatro comisiones del CMM sirven a la comunidad mundial de iglesias afines al anabautismo, en las \u00e1reas de diaconado, fe y vida, paz y misiones. Las comisiones preparan materiales para la consideraci\u00f3n del Concilio General, brindan gu\u00eda y proponen recursos a las iglesias miembros, adem\u00e1s, propician redes [&hellip;]","og_url":"https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/","og_site_name":"Mennonite World Conference","article_publisher":"https:\/\/www.facebook.com\/MennoniteWorldConference","article_published_time":"2016-12-19T00:00:00+00:00","article_modified_time":"2024-12-10T18:00:25+00:00","og_image":[{"width":1689,"height":1392,"url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/2-ghana_26-11_v1.jpg","type":"image\/jpeg"}],"author":"mennworldcon","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/#article","isPartOf":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/"},"author":{"name":"mennworldcon","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/person\/11f6ae0d7d1868ba20a1cc27f067c836"},"headline":"Se necesita su luz","datePublished":"2016-12-19T00:00:00+00:00","dateModified":"2024-12-10T18:00:25+00:00","mainEntityOfPage":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/"},"wordCount":872,"publisher":{"@id":"https:\/\/mwc-cmm.org\/en\/#organization"},"image":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/#primaryimage"},"thumbnailUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/2-ghana_26-11_v1.jpg","keywords":["Comisi\u00f3n de Di\u00e1conos","Comisi\u00f3n de Paz","Deacons Commission","Henk Stenvers"],"articleSection":["De Nuestros L\u00edderes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/","url":"https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/","name":"Se necesita su luz - Mennonite World Conference","isPartOf":{"@id":"https:\/\/mwc-cmm.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/#primaryimage"},"image":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/#primaryimage"},"thumbnailUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/2-ghana_26-11_v1.jpg","datePublished":"2016-12-19T00:00:00+00:00","dateModified":"2024-12-10T18:00:25+00:00","breadcrumb":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/#primaryimage","url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/2-ghana_26-11_v1.jpg","contentUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/2-ghana_26-11_v1.jpg","width":1689,"height":1392},{"@type":"BreadcrumbList","@id":"https:\/\/mwc-cmm.org\/es\/stories\/your-light-is-needed-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mwc-cmm.org\/es\/"},{"@type":"ListItem","position":2,"name":"Se necesita su luz"}]},{"@type":"WebSite","@id":"https:\/\/mwc-cmm.org\/en\/#website","url":"https:\/\/mwc-cmm.org\/en\/","name":"Mennonite World Conference","description":"A communion of Anabaptist-related churches","publisher":{"@id":"https:\/\/mwc-cmm.org\/en\/#organization"},"alternateName":"MWC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mwc-cmm.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mwc-cmm.org\/en\/#organization","name":"Mennonite World Conference","alternateName":"MWC","url":"https:\/\/mwc-cmm.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2026\/01\/MWC_Sig_Blue_Horiz_webheader1-logo.svg","contentUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2026\/01\/MWC_Sig_Blue_Horiz_webheader1-logo.svg","width":786,"height":82,"caption":"Mennonite World Conference"},"image":{"@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MennoniteWorldConference","https:\/\/www.linkedin.com\/company\/mennonite-world-conference-mwc\/","https:\/\/www.instagram.com\/mwcmm\/","https:\/\/www.youtube.com\/user\/mwccmm","https:\/\/bsky.app\/profile\/mwcmm.bsky.social"]},{"@type":"Person","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/person\/11f6ae0d7d1868ba20a1cc27f067c836","name":"mennworldcon","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g","caption":"mennworldcon"},"sameAs":["https:\/\/mwc-cmm.org"],"url":"https:\/\/mwc-cmm.org\/es\/stories\/author\/mennworldcon\/"}]}},"_links":{"self":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/posts\/8675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/comments?post=8675"}],"version-history":[{"count":0,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/posts\/8675\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/media\/88384"}],"wp:attachment":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/media?parent=8675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/categories?post=8675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/tags?post=8675"},{"taxonomy":"network","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/network?post=8675"},{"taxonomy":"eventcategory","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/eventcategory?post=8675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}