{"id":8482,"date":"2014-11-26T00:00:00","date_gmt":"2014-11-26T00:00:00","guid":{"rendered":"https:\/\/mwc-cmm.org\/local-tours-add-flavor-to-pa-2015-experience-3\/"},"modified":"2024-12-10T17:59:01","modified_gmt":"2024-12-10T17:59:01","slug":"local-tours-add-flavor-to-pa-2015-experience-3","status":"publish","type":"post","link":"https:\/\/mwc-cmm.org\/es\/stories\/local-tours-add-flavor-to-pa-2015-experience-3\/","title":{"rendered":"Excursiones locales le agregan sabor a la experiencia de \u201cPA 2015\u201d"},"content":{"rendered":"<p>Harrisburg, PA, EE.UU.\u2013 Los inscriptos en \u201cPA 2015\u201d podr\u00e1n elegir entre 47 excursiones al asistir a la Asamblea del Congreso Mundial Menonita, a realizarse el 21-26 de julio de 2015, en Harrisburg, PA.<\/p>\n<p>El lunes 20 de julio se llevar\u00e1n a cabo diez excursiones de <a href=\"http:\/\/www.mwc-cmm.org\/article\/tours-de-un-d%C3%ADa-de-la-asamblea\"><u>jornada completa<\/u><\/a>. Los inscriptos podr\u00e1n optar por visitar Washington, D.C., Philadelphia, New York City y varias comunidades anabautistas del este de Pennsylvania. Una consiste en un d\u00eda completo en Lancaster County, donde los participantes podr\u00e1n conocer a menonitas<em> y Old Order Amish<\/em>, cenar en un hogar <em>Amish<\/em> y compartir una velada de canto con cuatro grupos <em>Old Order<\/em>.<\/p>\n<p>Las excursiones de <a href=\"http:\/\/www.mwc-cmm.org\/article\/tours-de-medio-d%C3%ADa-durante-la-asamblea-del-cmm?language=es\"><u>media jornada<\/u><\/a> que se ofrecen durante la Asamblea enfocan en las siguientes \u00e1reas tem\u00e1ticas: sitios hist\u00f3ricos locales de grupos menonitas afines, actividades y lugares de anabautistas actuales, historia de Estados Unidos, temas de inter\u00e9s general y para la familia.<\/p>\n<p>A continuaci\u00f3n, algunos de los destinos de estas 37 excursiones de media jornada: emprendimientos Amish no rurales; lugares donde viven pueblos originarios de Estados Unidos, y tambi\u00e9n Lancaster Longhouse de los ind\u00edgenas de la zona boscosa del este; sitios de la ruta de escape clandestino de esclavos de 1800-1860 (casas, t\u00faneles y caminos), usada para ayudar a los esclavos afroamericanos; y la Escuela Industrial Ind\u00edgena Carlisle, dise\u00f1ada para asimilar a la cultura predominante a los ni\u00f1os de pueblos originarios de Estados Unidos provenientes de 140 tribus (1879-1918).<\/p>\n<p>Otras excursiones incluyen: visitas a un lugar de reuniones de los menonitas <em>Old Order<\/em> actualmente en uso, y una tienda de carruajes tipo sulky; Cloister de Ephrata, donde se public\u00f3 \u201cEl espejo de los m\u00e1rtires\u201d por primera vez en alem\u00e1n; y un vivero que emplea a trabajadores golondrinas de M\u00e9xico, la congregaci\u00f3n de los Hermanos en Cristo de habla hispana a la que pertenecen muchos de ellos, e historias de los trabajadores migrantes.<\/p>\n<p>Tambi\u00e9n habr\u00e1 las siguientes opciones: un recorrido por la cocina <em>Pennsylvania Dutch<\/em>; excursiones a pie por el centro hist\u00f3rico de Lancaster, y el pueblo cercano de Strasburg; una visita a las tres granjas de York County, que funcionan a peque\u00f1a escala de modo sustentable; navegar en kayak por el r\u00edo Susquehanna; y hacer trekking en el sendero de Appalachia.<\/p>\n<p>\u201cEl Complejo de<em> Farm Show <\/em>est\u00e1 ubicado en una hermosa zona hist\u00f3rica con una gran riqueza cultural, en el sudeste de Pennsylvania\u201d, dice Howard Good, Coordinador Nacional de PA 2015. \u201cQuisi\u00e9ramos que los inscriptos puedan visitar sitios hist\u00f3ricos y participar en actividades locales mientras est\u00e9n en la Asamblea. Hemos organizado a los anfitriones y el transporte de tal manera que nuestros invitados puedan aprovechar al m\u00e1ximo esta experiencia.\u201d<\/p>\n<p>Informaci\u00f3n m\u00e1s detallada de todas las excursiones est\u00e1 disponible en el formulario de inscripci\u00f3n de \u201c<a href=\"http:\/\/www.mwc-cmm.org\/pennsylvania-2015?language=es&#038;language=es\">PA 2015<\/a>\u201d.<\/p>\n<p><em>Comunicado del CMM por Phyllis Pellman Good de Lancaster, PA, escritora y redactora del Congreso Mundial Menonita.  <\/em><\/p>\n<p><em><img decoding=\"async\" alt=\"\" data-src=\"\/sites\/default\/files\/website_files\/mwc_local_tours_2.jpg\" style=\"width: 300px; margin: 5px 10px; float: left; height: 450px;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/em><\/p>\n<p>Una opci\u00f3n para los participantes de la Asamblea ser\u00eda una visita al Centro de Recursos Materiales, un proyecto del Comit\u00e9 Central Menonita en Ephrata, Pennsylvania. El centro es la sede para la recolecci\u00f3n de art\u00edculos donados por la gente, que responde a pedidos de los asociados del MCC en lugares con necesidades apremiantes.<\/p>\n<p>Foto del MCC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NULL<\/p>\n","protected":false},"author":1,"featured_media":86074,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"network":[],"eventcategory":[1493],"class_list":["post-8482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","eventcategory-assembly-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Excursiones locales le agregan sabor a la experiencia de \u201cPA 2015\u201d - Mennonite World Conference<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mwc-cmm.org\/en\/stories\/local-tours-add-flavor-to-pa-2015-experience\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Excursiones locales le agregan sabor a la experiencia de \u201cPA 2015\u201d - Mennonite World Conference\" \/>\n<meta property=\"og:description\" content=\"NULL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mwc-cmm.org\/en\/stories\/local-tours-add-flavor-to-pa-2015-experience\/\" \/>\n<meta property=\"og:site_name\" content=\"Mennonite World Conference\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MennoniteWorldConference\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-26T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-10T17:59:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/mwc_local_tours_1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1714\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mennworldcon\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/stories\\\/local-tours-add-flavor-to-pa-2015-experience\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/stories\\\/local-tours-add-flavor-to-pa-2015-experience\\\/\"},\"author\":{\"name\":\"mennworldcon\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/person\\\/11f6ae0d7d1868ba20a1cc27f067c836\"},\"headline\":\"Excursiones locales le agregan sabor a la experiencia de \u201cPA 2015\u201d\",\"datePublished\":\"2014-11-26T00:00:00+00:00\",\"dateModified\":\"2024-12-10T17:59:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/stories\\\/local-tours-add-flavor-to-pa-2015-experience\\\/\"},\"wordCount\":561,\"publisher\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/stories\\\/local-tours-add-flavor-to-pa-2015-experience\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/mwc_local_tours_1-scaled.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/stories\\\/local-tours-add-flavor-to-pa-2015-experience\\\/\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/stories\\\/local-tours-add-flavor-to-pa-2015-experience\\\/\",\"name\":\"Excursiones locales le agregan sabor a la experiencia de \u201cPA 2015\u201d - Mennonite World Conference\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/stories\\\/local-tours-add-flavor-to-pa-2015-experience\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/stories\\\/local-tours-add-flavor-to-pa-2015-experience\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/mwc_local_tours_1-scaled.jpg\",\"datePublished\":\"2014-11-26T00:00:00+00:00\",\"dateModified\":\"2024-12-10T17:59:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/stories\\\/local-tours-add-flavor-to-pa-2015-experience\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/stories\\\/local-tours-add-flavor-to-pa-2015-experience\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/stories\\\/local-tours-add-flavor-to-pa-2015-experience\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/mwc_local_tours_1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/mwc_local_tours_1-scaled.jpg\",\"width\":2560,\"height\":1714},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/stories\\\/local-tours-add-flavor-to-pa-2015-experience\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Excursiones locales le agregan sabor a la experiencia de \u201cPA 2015\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/\",\"name\":\"Mennonite World Conference\",\"description\":\"A communion of Anabaptist-related churches\",\"publisher\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\"},\"alternateName\":\"MWC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\",\"name\":\"Mennonite World Conference\",\"alternateName\":\"MWC\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/MWC_Sig_Blue_Horiz_webheader1-logo.svg\",\"contentUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/MWC_Sig_Blue_Horiz_webheader1-logo.svg\",\"width\":786,\"height\":82,\"caption\":\"Mennonite World Conference\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MennoniteWorldConference\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mennonite-world-conference-mwc\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mwcmm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/mwccmm\",\"https:\\\/\\\/bsky.app\\\/profile\\\/mwcmm.bsky.social\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/person\\\/11f6ae0d7d1868ba20a1cc27f067c836\",\"name\":\"mennworldcon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g\",\"caption\":\"mennworldcon\"},\"sameAs\":[\"https:\\\/\\\/mwc-cmm.org\"],\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/author\\\/mennworldcon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Excursiones locales le agregan sabor a la experiencia de \u201cPA 2015\u201d - Mennonite World Conference","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mwc-cmm.org\/en\/stories\/local-tours-add-flavor-to-pa-2015-experience\/","og_locale":"es_ES","og_type":"article","og_title":"Excursiones locales le agregan sabor a la experiencia de \u201cPA 2015\u201d - Mennonite World Conference","og_description":"NULL","og_url":"https:\/\/mwc-cmm.org\/en\/stories\/local-tours-add-flavor-to-pa-2015-experience\/","og_site_name":"Mennonite World Conference","article_publisher":"https:\/\/www.facebook.com\/MennoniteWorldConference","article_published_time":"2014-11-26T00:00:00+00:00","article_modified_time":"2024-12-10T17:59:01+00:00","og_image":[{"width":2560,"height":1714,"url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/mwc_local_tours_1-scaled.jpg","type":"image\/jpeg"}],"author":"mennworldcon","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mwc-cmm.org\/en\/stories\/local-tours-add-flavor-to-pa-2015-experience\/#article","isPartOf":{"@id":"https:\/\/mwc-cmm.org\/en\/stories\/local-tours-add-flavor-to-pa-2015-experience\/"},"author":{"name":"mennworldcon","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/person\/11f6ae0d7d1868ba20a1cc27f067c836"},"headline":"Excursiones locales le agregan sabor a la experiencia de \u201cPA 2015\u201d","datePublished":"2014-11-26T00:00:00+00:00","dateModified":"2024-12-10T17:59:01+00:00","mainEntityOfPage":{"@id":"https:\/\/mwc-cmm.org\/en\/stories\/local-tours-add-flavor-to-pa-2015-experience\/"},"wordCount":561,"publisher":{"@id":"https:\/\/mwc-cmm.org\/en\/#organization"},"image":{"@id":"https:\/\/mwc-cmm.org\/en\/stories\/local-tours-add-flavor-to-pa-2015-experience\/#primaryimage"},"thumbnailUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/mwc_local_tours_1-scaled.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mwc-cmm.org\/en\/stories\/local-tours-add-flavor-to-pa-2015-experience\/","url":"https:\/\/mwc-cmm.org\/en\/stories\/local-tours-add-flavor-to-pa-2015-experience\/","name":"Excursiones locales le agregan sabor a la experiencia de \u201cPA 2015\u201d - Mennonite World Conference","isPartOf":{"@id":"https:\/\/mwc-cmm.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mwc-cmm.org\/en\/stories\/local-tours-add-flavor-to-pa-2015-experience\/#primaryimage"},"image":{"@id":"https:\/\/mwc-cmm.org\/en\/stories\/local-tours-add-flavor-to-pa-2015-experience\/#primaryimage"},"thumbnailUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/mwc_local_tours_1-scaled.jpg","datePublished":"2014-11-26T00:00:00+00:00","dateModified":"2024-12-10T17:59:01+00:00","breadcrumb":{"@id":"https:\/\/mwc-cmm.org\/en\/stories\/local-tours-add-flavor-to-pa-2015-experience\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mwc-cmm.org\/en\/stories\/local-tours-add-flavor-to-pa-2015-experience\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mwc-cmm.org\/en\/stories\/local-tours-add-flavor-to-pa-2015-experience\/#primaryimage","url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/mwc_local_tours_1-scaled.jpg","contentUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/mwc_local_tours_1-scaled.jpg","width":2560,"height":1714},{"@type":"BreadcrumbList","@id":"https:\/\/mwc-cmm.org\/en\/stories\/local-tours-add-flavor-to-pa-2015-experience\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mwc-cmm.org\/es\/"},{"@type":"ListItem","position":2,"name":"Excursiones locales le agregan sabor a la experiencia de \u201cPA 2015\u201d"}]},{"@type":"WebSite","@id":"https:\/\/mwc-cmm.org\/en\/#website","url":"https:\/\/mwc-cmm.org\/en\/","name":"Mennonite World Conference","description":"A communion of Anabaptist-related churches","publisher":{"@id":"https:\/\/mwc-cmm.org\/en\/#organization"},"alternateName":"MWC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mwc-cmm.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mwc-cmm.org\/en\/#organization","name":"Mennonite World Conference","alternateName":"MWC","url":"https:\/\/mwc-cmm.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2026\/01\/MWC_Sig_Blue_Horiz_webheader1-logo.svg","contentUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2026\/01\/MWC_Sig_Blue_Horiz_webheader1-logo.svg","width":786,"height":82,"caption":"Mennonite World Conference"},"image":{"@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MennoniteWorldConference","https:\/\/www.linkedin.com\/company\/mennonite-world-conference-mwc\/","https:\/\/www.instagram.com\/mwcmm\/","https:\/\/www.youtube.com\/user\/mwccmm","https:\/\/bsky.app\/profile\/mwcmm.bsky.social"]},{"@type":"Person","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/person\/11f6ae0d7d1868ba20a1cc27f067c836","name":"mennworldcon","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06fdc0dc81c157dfdb82ec42f252178a22307808988d22c043f9eb96f1e0fe80?s=96&d=mm&r=g","caption":"mennworldcon"},"sameAs":["https:\/\/mwc-cmm.org"],"url":"https:\/\/mwc-cmm.org\/es\/stories\/author\/mennworldcon\/"}]}},"_links":{"self":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/posts\/8482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/comments?post=8482"}],"version-history":[{"count":0,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/posts\/8482\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/media\/86074"}],"wp:attachment":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/media?parent=8482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/categories?post=8482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/tags?post=8482"},{"taxonomy":"network","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/network?post=8482"},{"taxonomy":"eventcategory","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/eventcategory?post=8482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}