{"id":126375,"date":"2015-07-24T02:58:42","date_gmt":"2015-07-24T02:58:42","guid":{"rendered":"https:\/\/mwc-cmm.org\/stories\/shuttles-bring-people-together\/"},"modified":"2026-03-25T13:16:01","modified_gmt":"2026-03-25T13:16:01","slug":"shuttles-bring-people-together","status":"publish","type":"post","link":"https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/","title":{"rendered":"Los buses de traslado unen a la gente"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La red de transportaci<em>\u00f3<\/em><em>n produce amigos entre gente desconocida<\/em><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Por Karla Braun<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Harrisburg, Pensilvania, EE.UU. \u2013 \u201cTodo lo que veo son sonrisas\u201d, dice Brenda Burkholder, voluntaria en la mesa de transporte hacia las casa de hospedaje. Muchos de los m\u00e1s de 7.200 hu\u00e9spedes de 56 pa\u00edses registrados para Pensilvania 2015 viajan cada d\u00eda a sus lugares de hospedaje desde el Complejo de Exposici\u00f3n Agr\u00edcola en los buses de traslado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de la red de traslado de aeropuertos, tres sistemas diferentes de bus operan durante la asamblea: hoteles, los dormitorios del \u201cMessiah College\u201d, y las casas de hospedaje.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leon y Nancy Stauffer, creadores del cat\u00e1logo de \u201c<em>Mennonite Your Way<\/em>\u201d para viajeros, lideran el sistema de traslado para aquellos invitados a la Asamblea que se hospedan en casas de anabautistas locales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pareja Stauffer emple\u00f3 21 buses de \u201cElite Coach\u201d y \u201cExecutive Coach\u201d, compa\u00f1\u00edas de Lancaster aliadas a la comunidad menonita. Cada bus transporta entre 25 y 40 hu\u00e9spedes desde el complejo hasta un centro de recogida, de donde las familias anfitrionas los llevan a sus propias casas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adicionalmente, un anfitri\u00f3n o anfitriona viaja con cada bus atendiendo y respondiendo a cualquier inquietud.<\/p>\n\n\n\n<figure class=\"wp-block-image alignright size-medium\"><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2015\/07\/Shuttles-MikeLenaBrown-creditKB-300x225.jpg\" alt=\"\" class=\"wp-image-126371 lazyload\" data-srcset=\"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2015\/07\/Shuttles-MikeLenaBrown-creditKB-300x225.jpg 300w, https:\/\/mwc-cmm.org\/wp-content\/uploads\/2015\/07\/Shuttles-MikeLenaBrown-creditKB-1024x768.jpg 1024w, https:\/\/mwc-cmm.org\/wp-content\/uploads\/2015\/07\/Shuttles-MikeLenaBrown-creditKB-768x576.jpg 768w, https:\/\/mwc-cmm.org\/wp-content\/uploads\/2015\/07\/Shuttles-MikeLenaBrown-creditKB-1536x1152.jpg 1536w, https:\/\/mwc-cmm.org\/wp-content\/uploads\/2015\/07\/Shuttles-MikeLenaBrown-creditKB-2048x1536.jpg 2048w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><figcaption class=\"wp-element-caption\">Mike and Lena Brown<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Mike y Lena Brown de la Conferencia Menonita de Lancaster sirven como anfitriones para uno de los buses. Ellos dicen que hay un ambiente muy animado entre los viajeros que provienen de nueve pa\u00edses diferentes. Algunos comentan que el traslado de casi una hora de recorrido se convierte en una gira que les permite disfrutar el escenario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los primeros d\u00edas hubo algunos problemas cuando las exigencias del viaje \u2013 vuelos atrasados o perdidos y entrevistas largas en la aduana \u2013 interrumpieron los horarios del sistema de traslado. Se perdieron algunas conexiones de un sistema de traslado a otro y los anfitriones tuvieron que volver a casa sin hu\u00e9spedes la primera noche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leon exalta lo divertido de todos los que est\u00e1n involucrados en el hospedaje. Aprecia \u201csu flexibilidad incluso con el tipo de caos que tuvimos. Siguen sonriendo aut\u00e9nticamente cuando se re\u00fanen\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La labor de los Stauffer, de conseguir familias anfitrionas, comenz\u00f3 dos a\u00f1os antes del evento del 21 al 25 de julio. Ocup\u00f3 sus energ\u00edas a tiempo completo durante los \u00faltimos meses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hacer la conexi\u00f3n entre hu\u00e9spedes y anfitriones no es tan sencillo como lo es meramente escribir nombres en una lista. Los Stauffer tuvieron en cuenta alergias a los animales dom\u00e9sticos, necesidades de accesibilidad, preferencias en quedarse con amigos, hospedar a personas de un pa\u00eds en particular o hablantes de un idioma en particular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cOramos mucho\u201d, dice Nancy.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hubo inscripci\u00f3n de 800 hogares anfitriones con uno a siete hu\u00e9spedes en cada hogar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Brown, como muchos de los anfitriones de bus, tambi\u00e9n tienen hu\u00e9spedes en su casa. Lo ven como una oportunidad de servir y conocer personas muy interesantes. La gente local son simplemente personas, dice Mike sonriendo, pero los visitantes son l\u00edderes de quienes tenemos mucho que aprender mientras caminamos juntos con Dios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Karla Braun ha sido editora asociada del <\/em>MB Herald <em>(revista de la Conferencia Canadiense de las Iglesias de Hermanos Menonitas) y pasar\u00e1 a ser editora de <\/em>Courrier\/Correo\/Courier <em>despu\u00e9s de la Asamblea).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La red de transportaci\u00f3n produce amigos entre gente desconocida Por Karla Braun Harrisburg, Pensilvania, EE.UU. \u2013 \u201cTodo lo que veo son sonrisas\u201d, dice Brenda Burkholder, voluntaria en la mesa de transporte hacia las casa de hospedaje. Muchos de los m\u00e1s de 7.200 hu\u00e9spedes de 56 pa\u00edses registrados para Pensilvania 2015 viajan cada d\u00eda a sus [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":126371,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1896],"tags":[1154,1698,2215,2216,2217,2218,2219,2220,2221,1053,1899,1900,1576,1577,2067],"network":[],"eventcategory":[299],"class_list":["post-126375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tomigrate","tag-assembly-es","tag-assembly","tag-brenda-burkholder","tag-bus-hosts","tag-homestay","tag-lena-brown","tag-leon-stauffer","tag-mike-brown","tag-nancy-stauffer","tag-pa-2015-es","tag-pa2015","tag-pa2015-assembly-experiences","tag-pensilvania","tag-tomigrate","tag-venue-logistics","eventcategory-assembly"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los buses de traslado unen a la gente - Mennonite World Conference<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los buses de traslado unen a la gente - Mennonite World Conference\" \/>\n<meta property=\"og:description\" content=\"La red de transportaci\u00f3n produce amigos entre gente desconocida Por Karla Braun Harrisburg, Pensilvania, EE.UU. \u2013 \u201cTodo lo que veo son sonrisas\u201d, dice Brenda Burkholder, voluntaria en la mesa de transporte hacia las casa de hospedaje. Muchos de los m\u00e1s de 7.200 hu\u00e9spedes de 56 pa\u00edses registrados para Pensilvania 2015 viajan cada d\u00eda a sus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/\" \/>\n<meta property=\"og:site_name\" content=\"Mennonite World Conference\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MennoniteWorldConference\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-24T02:58:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T13:16:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2015\/07\/Shuttles-MikeLenaBrown-creditKB-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karla Braun\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/shuttles-bring-people-together\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/shuttles-bring-people-together\\\/\"},\"author\":{\"name\":\"Karla Braun\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/person\\\/9cb7cad70e3a0ac2b145c3441df0dc08\"},\"headline\":\"Los buses de traslado unen a la gente\",\"datePublished\":\"2015-07-24T02:58:42+00:00\",\"dateModified\":\"2026-03-25T13:16:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/shuttles-bring-people-together\\\/\"},\"wordCount\":551,\"publisher\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/shuttles-bring-people-together\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Shuttles-MikeLenaBrown-creditKB-scaled.jpg\",\"keywords\":[\"Asamblea\",\"assembly\",\"Brenda Burkholder\",\"bus hosts\",\"homestay\",\"Lena Brown\",\"Leon Stauffer\",\"Mike Brown\",\"Nancy Stauffer\",\"PA 2015\",\"PA2015\",\"PA2015 Assembly experiences\",\"Pensilvania\",\"tomigrate\",\"venue &amp; logistics\"],\"articleSection\":[\"tomigrate\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/shuttles-bring-people-together\\\/\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/shuttles-bring-people-together\\\/\",\"name\":\"Los buses de traslado unen a la gente - Mennonite World Conference\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/shuttles-bring-people-together\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/shuttles-bring-people-together\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Shuttles-MikeLenaBrown-creditKB-scaled.jpg\",\"datePublished\":\"2015-07-24T02:58:42+00:00\",\"dateModified\":\"2026-03-25T13:16:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/shuttles-bring-people-together\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/shuttles-bring-people-together\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/shuttles-bring-people-together\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Shuttles-MikeLenaBrown-creditKB-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Shuttles-MikeLenaBrown-creditKB-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"Mike and Lena Brown\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/shuttles-bring-people-together\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los buses de traslado unen a la gente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/\",\"name\":\"Mennonite World Conference\",\"description\":\"A communion of Anabaptist-related churches\",\"publisher\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\"},\"alternateName\":\"MWC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\",\"name\":\"Mennonite World Conference\",\"alternateName\":\"MWC\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/MWC_Sig_Blue_Horiz_webheader1-logo.svg\",\"contentUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/MWC_Sig_Blue_Horiz_webheader1-logo.svg\",\"width\":786,\"height\":82,\"caption\":\"Mennonite World Conference\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MennoniteWorldConference\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mennonite-world-conference-mwc\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mwcmm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/mwccmm\",\"https:\\\/\\\/bsky.app\\\/profile\\\/mwcmm.bsky.social\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/person\\\/9cb7cad70e3a0ac2b145c3441df0dc08\",\"name\":\"Karla Braun\",\"pronouns\":\"she\\\/her\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/330c84143dc3a1bf6e7887f828baae23c874bf72d5eedb0461d88c0725087370?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/330c84143dc3a1bf6e7887f828baae23c874bf72d5eedb0461d88c0725087370?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/330c84143dc3a1bf6e7887f828baae23c874bf72d5eedb0461d88c0725087370?s=96&d=mm&r=g\",\"caption\":\"Karla Braun\"},\"description\":\"Karla Braun serves as editor and website coordinator for MWC since 2015.\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/stories\\\/author\\\/karla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los buses de traslado unen a la gente - Mennonite World Conference","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/","og_locale":"es_ES","og_type":"article","og_title":"Los buses de traslado unen a la gente - Mennonite World Conference","og_description":"La red de transportaci\u00f3n produce amigos entre gente desconocida Por Karla Braun Harrisburg, Pensilvania, EE.UU. \u2013 \u201cTodo lo que veo son sonrisas\u201d, dice Brenda Burkholder, voluntaria en la mesa de transporte hacia las casa de hospedaje. Muchos de los m\u00e1s de 7.200 hu\u00e9spedes de 56 pa\u00edses registrados para Pensilvania 2015 viajan cada d\u00eda a sus [&hellip;]","og_url":"https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/","og_site_name":"Mennonite World Conference","article_publisher":"https:\/\/www.facebook.com\/MennoniteWorldConference","article_published_time":"2015-07-24T02:58:42+00:00","article_modified_time":"2026-03-25T13:16:01+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2015\/07\/Shuttles-MikeLenaBrown-creditKB-scaled.jpg","type":"image\/jpeg"}],"author":"Karla Braun","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/#article","isPartOf":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/"},"author":{"name":"Karla Braun","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/person\/9cb7cad70e3a0ac2b145c3441df0dc08"},"headline":"Los buses de traslado unen a la gente","datePublished":"2015-07-24T02:58:42+00:00","dateModified":"2026-03-25T13:16:01+00:00","mainEntityOfPage":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/"},"wordCount":551,"publisher":{"@id":"https:\/\/mwc-cmm.org\/en\/#organization"},"image":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/#primaryimage"},"thumbnailUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2015\/07\/Shuttles-MikeLenaBrown-creditKB-scaled.jpg","keywords":["Asamblea","assembly","Brenda Burkholder","bus hosts","homestay","Lena Brown","Leon Stauffer","Mike Brown","Nancy Stauffer","PA 2015","PA2015","PA2015 Assembly experiences","Pensilvania","tomigrate","venue &amp; logistics"],"articleSection":["tomigrate"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/","url":"https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/","name":"Los buses de traslado unen a la gente - Mennonite World Conference","isPartOf":{"@id":"https:\/\/mwc-cmm.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/#primaryimage"},"image":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/#primaryimage"},"thumbnailUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2015\/07\/Shuttles-MikeLenaBrown-creditKB-scaled.jpg","datePublished":"2015-07-24T02:58:42+00:00","dateModified":"2026-03-25T13:16:01+00:00","breadcrumb":{"@id":"https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/#primaryimage","url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2015\/07\/Shuttles-MikeLenaBrown-creditKB-scaled.jpg","contentUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2015\/07\/Shuttles-MikeLenaBrown-creditKB-scaled.jpg","width":2560,"height":1920,"caption":"Mike and Lena Brown"},{"@type":"BreadcrumbList","@id":"https:\/\/mwc-cmm.org\/es\/stories\/shuttles-bring-people-together\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mwc-cmm.org\/es\/"},{"@type":"ListItem","position":2,"name":"Los buses de traslado unen a la gente"}]},{"@type":"WebSite","@id":"https:\/\/mwc-cmm.org\/en\/#website","url":"https:\/\/mwc-cmm.org\/en\/","name":"Mennonite World Conference","description":"A communion of Anabaptist-related churches","publisher":{"@id":"https:\/\/mwc-cmm.org\/en\/#organization"},"alternateName":"MWC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mwc-cmm.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mwc-cmm.org\/en\/#organization","name":"Mennonite World Conference","alternateName":"MWC","url":"https:\/\/mwc-cmm.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2026\/01\/MWC_Sig_Blue_Horiz_webheader1-logo.svg","contentUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2026\/01\/MWC_Sig_Blue_Horiz_webheader1-logo.svg","width":786,"height":82,"caption":"Mennonite World Conference"},"image":{"@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MennoniteWorldConference","https:\/\/www.linkedin.com\/company\/mennonite-world-conference-mwc\/","https:\/\/www.instagram.com\/mwcmm\/","https:\/\/www.youtube.com\/user\/mwccmm","https:\/\/bsky.app\/profile\/mwcmm.bsky.social"]},{"@type":"Person","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/person\/9cb7cad70e3a0ac2b145c3441df0dc08","name":"Karla Braun","pronouns":"she\/her","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/330c84143dc3a1bf6e7887f828baae23c874bf72d5eedb0461d88c0725087370?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/330c84143dc3a1bf6e7887f828baae23c874bf72d5eedb0461d88c0725087370?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/330c84143dc3a1bf6e7887f828baae23c874bf72d5eedb0461d88c0725087370?s=96&d=mm&r=g","caption":"Karla Braun"},"description":"Karla Braun serves as editor and website coordinator for MWC since 2015.","url":"https:\/\/mwc-cmm.org\/es\/stories\/author\/karla\/"}]}},"_links":{"self":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/posts\/126375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/comments?post=126375"}],"version-history":[{"count":0,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/posts\/126375\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/media\/126371"}],"wp:attachment":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/media?parent=126375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/categories?post=126375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/tags?post=126375"},{"taxonomy":"network","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/network?post=126375"},{"taxonomy":"eventcategory","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/eventcategory?post=126375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}