{"id":17528,"date":"2023-11-19T17:39:24","date_gmt":"2023-11-19T17:39:24","guid":{"rendered":"https:\/\/mwc-cmm.org\/en\/resources\/awfs-2024-carta\/"},"modified":"2024-12-12T18:08:27","modified_gmt":"2024-12-12T18:08:27","slug":"awfs-2024-carta","status":"publish","type":"mwcresource","link":"https:\/\/mwc-cmm.org\/es\/resources\/awfs-2024-carta\/","title":{"rendered":"AWFS 2024 Carta"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Septiembre 2023<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A: Todas las Iglesias Menonitas, Hermanos en Cristo e iglesias afines al anabautismo de todo el mundo&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apreciados hermanos y hermanas&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con gran alegr\u00eda compartimos con ustedes los recursos para el&nbsp;<a href=\"https:\/\/mwc-cmm.org\/es\/domingo-de-la-fraternidad-anabautista-mundial\"><strong>Domingo de la Fraternidad Anabautista Mundial<\/strong><\/a>&nbsp;(AWFS, por sus siglas en ingl\u00e9s). Cada a\u00f1o animamos a las iglesias afines al anabautismo alrededor del mundo, para que utilicen un tema com\u00fan en alguno de sus servicios con el fin de conectarse con nuestra familia anabautista a nivel mundial. Muchas iglesias eligen celebrarlo el domingo m\u00e1s cercano al&nbsp;<strong>21 de enero.<\/strong>&nbsp;En esta fecha, en 1525, tuvo lugar el primer bautismo en Z\u00farich, Suiza.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El AWFS es una oportunidad para recordar en nuestras comunidades de fe que somos parte de un solo cuerpo, compuesto por muchas tribus, lenguas y naciones (Apocalipsis 7,9).&nbsp;&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Es una invitaci\u00f3n a proclamar en forma visible que entre nosotros ya no hay discriminaci\u00f3n por diferencias de raza, estrato social o g\u00e9nero (G\u00e1latas 3,28).\u00a0\u00a0<\/li>\n\n\n\n<li>Es un d\u00eda especial para evidenciar que vivimos una nueva vida dentro de una nueva sociedad, en la que nos apoyamos mutuamente, sostenemos a aquellos que sufren, servimos al mundo y, de forma interdependiente, aprendemos unos de otros lo que significa seguir a Jes\u00fas.\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En este d\u00eda celebramos que en Cristo, y por el poder del Esp\u00edritu Santo, las barreras culturales y los nacionalismos que antes nos separaban han sido vencidos en la cruz.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada a\u00f1o, una parte de nuestra comunidad mundial prepara algunos materiales que pueden ser utilizados para el AWFS. El tema para el AWFS 2024 es&nbsp;<strong>\u201cMosaico: Convirti\u00e9ndonos en parte del gran panorama de Dios\u201d<\/strong>, ha sido preparado desde la experiencia de nuestras hermanos y hermanas de Am\u00e9rica Latina.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los materiales en menci\u00f3n incluyen textos b\u00edblicos, oraciones, sugerencias de canciones, ideas para el serm\u00f3n e historias, entre otros recursos. Esperamos que estos materiales faciliten la preparaci\u00f3n del AWFS en cada congregaci\u00f3n local.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Animamos a su iglesia nacional a elegir y a adaptar estos recursos de manera que sean \u00fatiles para su contexto local, incluso a traducirlos en caso de ser necesario. Por favor comparta y distribuya estos recursos a todas las congregaciones locales, anim\u00e1ndoles a celebrar el Domingo de la Fraternidad Anabautista Mundial en alg\u00fan momento del 2024. Vea el documento adjunto, y m\u00e1s en l\u00ednea en&nbsp;<a href=\"http:\/\/mwc-cmm.org\/domingofraternidadanabautistamundial\">mwc-cmm.org\/domingofraternidadanabautistamundial.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las ofrendas recibidas durante ese d\u00eda y enviadas posteriormente al CMM ayudar\u00e1n a cada iglesia miembro a cubrir su aporte proporcional justo y servir\u00e1n para que nuestra comunidad mundial pueda seguir adelante en su deseo de ser un reflejo del Reino de Dios en medio de nuestra sociedad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el CMM recibimos con agrado sus comentarios, fotos y reflexiones acerca del AWFS, con la finalidad de compartirlos con otros miembros de nuestra familia mundial de fe. Pueden compartir sus fotos e historias al correo electr\u00f3nico&nbsp;<a href=\"mailto:photos@mwc-cmm.org\">photos@mwc-cmm.org<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracia y paz,&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00e9sar Garc\u00eda, Secretario General<br>Arli Klassen,&nbsp;Representantes Regionales Coordinadora<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/mwc-cmm.org\/es\/resources\/domingo-de-la-fraternidad-anabautista-mundial-2024\"><img decoding=\"async\" width=\"500\" height=\"120\" data-src=\"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/image-16.png\" alt=\"\" class=\"wp-image-106809 lazyload\" data-srcset=\"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/image-16.png 500w, https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/image-16-300x72.png 300w\" data-sizes=\"(max-width: 500px) 100vw, 500px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/120;\" \/><\/a><\/figure>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/awfs2024-letter-sp.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de awfs2024-letter-sp.\"><\/object><a id=\"wp-block-file--media-9cd7c2d4-b32b-4621-a51e-a40b0864bf8c\" href=\"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/awfs2024-letter-sp.pdf\">awfs2024-letter-sp<\/a><a href=\"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/awfs2024-letter-sp.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-9cd7c2d4-b32b-4621-a51e-a40b0864bf8c\">Download<\/a><\/div>\n","protected":false},"featured_media":0,"template":"","network":[],"resourcetype":[],"language":[168],"resourcecategory":[1366],"resourcetheme":[],"eventcategory":[],"class_list":["post-17528","mwcresource","type-mwcresource","status-publish","hentry","language-es","resourcecategory-worship-resource-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AWFS 2024 Carta - Mennonite World Conference<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mwc-cmm.org\/en\/resources\/awfs-2024-letter\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AWFS 2024 Carta - Mennonite World Conference\" \/>\n<meta property=\"og:description\" content=\"Septiembre 2023 A: Todas las Iglesias Menonitas, Hermanos en Cristo e iglesias afines al anabautismo de todo el mundo&nbsp; Apreciados hermanos y hermanas&nbsp; Con gran alegr\u00eda compartimos con ustedes los recursos para el&nbsp;Domingo de la Fraternidad Anabautista Mundial&nbsp;(AWFS, por sus siglas en ingl\u00e9s). Cada a\u00f1o animamos a las iglesias afines al anabautismo alrededor del mundo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mwc-cmm.org\/en\/resources\/awfs-2024-letter\/\" \/>\n<meta property=\"og:site_name\" content=\"Mennonite World Conference\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MennoniteWorldConference\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-12T18:08:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/image-16.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/resources\\\/awfs-2024-letter\\\/\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/resources\\\/awfs-2024-letter\\\/\",\"name\":\"AWFS 2024 Carta - Mennonite World Conference\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/resources\\\/awfs-2024-letter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/resources\\\/awfs-2024-letter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/image-16.png\",\"datePublished\":\"2023-11-19T17:39:24+00:00\",\"dateModified\":\"2024-12-12T18:08:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/resources\\\/awfs-2024-letter\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/resources\\\/awfs-2024-letter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/resources\\\/awfs-2024-letter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/image-16.png\",\"contentUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/image-16.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/resources\\\/awfs-2024-letter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mwc-cmm.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AWFS 2024 Carta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/\",\"name\":\"Mennonite World Conference\",\"description\":\"A communion of Anabaptist-related churches\",\"publisher\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\"},\"alternateName\":\"MWC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#organization\",\"name\":\"Mennonite World Conference\",\"alternateName\":\"MWC\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/MWC_Sig_Blue_Horiz_webheader1-logo.svg\",\"contentUrl\":\"https:\\\/\\\/mwc-cmm.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/MWC_Sig_Blue_Horiz_webheader1-logo.svg\",\"width\":786,\"height\":82,\"caption\":\"Mennonite World Conference\"},\"image\":{\"@id\":\"https:\\\/\\\/mwc-cmm.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MennoniteWorldConference\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mennonite-world-conference-mwc\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mwcmm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/mwccmm\",\"https:\\\/\\\/bsky.app\\\/profile\\\/mwcmm.bsky.social\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AWFS 2024 Carta - Mennonite World Conference","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mwc-cmm.org\/en\/resources\/awfs-2024-letter\/","og_locale":"es_ES","og_type":"article","og_title":"AWFS 2024 Carta - Mennonite World Conference","og_description":"Septiembre 2023 A: Todas las Iglesias Menonitas, Hermanos en Cristo e iglesias afines al anabautismo de todo el mundo&nbsp; Apreciados hermanos y hermanas&nbsp; Con gran alegr\u00eda compartimos con ustedes los recursos para el&nbsp;Domingo de la Fraternidad Anabautista Mundial&nbsp;(AWFS, por sus siglas en ingl\u00e9s). Cada a\u00f1o animamos a las iglesias afines al anabautismo alrededor del mundo, [&hellip;]","og_url":"https:\/\/mwc-cmm.org\/en\/resources\/awfs-2024-letter\/","og_site_name":"Mennonite World Conference","article_publisher":"https:\/\/www.facebook.com\/MennoniteWorldConference","article_modified_time":"2024-12-12T18:08:27+00:00","og_image":[{"width":500,"height":120,"url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/image-16.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mwc-cmm.org\/en\/resources\/awfs-2024-letter\/","url":"https:\/\/mwc-cmm.org\/en\/resources\/awfs-2024-letter\/","name":"AWFS 2024 Carta - Mennonite World Conference","isPartOf":{"@id":"https:\/\/mwc-cmm.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mwc-cmm.org\/en\/resources\/awfs-2024-letter\/#primaryimage"},"image":{"@id":"https:\/\/mwc-cmm.org\/en\/resources\/awfs-2024-letter\/#primaryimage"},"thumbnailUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/image-16.png","datePublished":"2023-11-19T17:39:24+00:00","dateModified":"2024-12-12T18:08:27+00:00","breadcrumb":{"@id":"https:\/\/mwc-cmm.org\/en\/resources\/awfs-2024-letter\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mwc-cmm.org\/en\/resources\/awfs-2024-letter\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mwc-cmm.org\/en\/resources\/awfs-2024-letter\/#primaryimage","url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/image-16.png","contentUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2024\/11\/image-16.png"},{"@type":"BreadcrumbList","@id":"https:\/\/mwc-cmm.org\/en\/resources\/awfs-2024-letter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mwc-cmm.org\/es\/"},{"@type":"ListItem","position":2,"name":"AWFS 2024 Carta"}]},{"@type":"WebSite","@id":"https:\/\/mwc-cmm.org\/en\/#website","url":"https:\/\/mwc-cmm.org\/en\/","name":"Mennonite World Conference","description":"A communion of Anabaptist-related churches","publisher":{"@id":"https:\/\/mwc-cmm.org\/en\/#organization"},"alternateName":"MWC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mwc-cmm.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mwc-cmm.org\/en\/#organization","name":"Mennonite World Conference","alternateName":"MWC","url":"https:\/\/mwc-cmm.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2026\/01\/MWC_Sig_Blue_Horiz_webheader1-logo.svg","contentUrl":"https:\/\/mwc-cmm.org\/wp-content\/uploads\/2026\/01\/MWC_Sig_Blue_Horiz_webheader1-logo.svg","width":786,"height":82,"caption":"Mennonite World Conference"},"image":{"@id":"https:\/\/mwc-cmm.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MennoniteWorldConference","https:\/\/www.linkedin.com\/company\/mennonite-world-conference-mwc\/","https:\/\/www.instagram.com\/mwcmm\/","https:\/\/www.youtube.com\/user\/mwccmm","https:\/\/bsky.app\/profile\/mwcmm.bsky.social"]}]}},"_links":{"self":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/mwcresource\/17528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/mwcresource"}],"about":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/types\/mwcresource"}],"wp:attachment":[{"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/media?parent=17528"}],"wp:term":[{"taxonomy":"network","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/network?post=17528"},{"taxonomy":"resourcetype","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/resourcetype?post=17528"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/language?post=17528"},{"taxonomy":"resourcecategory","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/resourcecategory?post=17528"},{"taxonomy":"resourcetheme","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/resourcetheme?post=17528"},{"taxonomy":"eventcategory","embeddable":true,"href":"https:\/\/mwc-cmm.org\/es\/wp-json\/wp\/v2\/eventcategory?post=17528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}